{"id":1015,"date":"2024-04-22T14:16:06","date_gmt":"2024-04-22T12:16:06","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/?p=1015"},"modified":"2024-04-22T14:16:06","modified_gmt":"2024-04-22T12:16:06","slug":"din-und-dke-zeigen-vorteile-von-smart-standards","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2024\/04\/22\/din-und-dke-zeigen-vorteile-von-smart-standards\/","title":{"rendered":"DIN und DKE zeigen Vorteile von SMART Standards"},"content":{"rendered":"<p>Der Einsatz von SMART Standards besitzt das Potenzial, den Umsatz eines Unternehmens um bis 60 Prozent zu steigern \u2013 der Digitalisierungsgrad der Unternehmen sowie der bereitgestellten Normen spielen dabei die entscheidende Rolle. Das haben DIN und DKE jetzt im Rahmen der Initiative Digitale Standards (IDiS) ermittelt. Untersucht wurde, wie sich der Einsatz von SMART Standards jeweils auf die Prozessqualit\u00e4t, die Produktqualit\u00e4t und das Umsatzpotenzial von Unternehmen auswirkt und welchen Einfluss sie auf die Besch\u00e4ftigten oder die Organisation haben. Der zeitliche Aufwand reduziert sich demnach deutlich. Mitarbeiterinnen und Mitarbeiter werden entlastet und k\u00f6nnen sich auf andere Aufgaben konzentrieren. Die Sachkosten lassen sich in etwa halbieren, w\u00e4hrend sich die Zahl der abgewickelten Auftr\u00e4ge im g\u00fcnstigsten Fall sogar verdoppeln l\u00e4sst.<\/p>\n<p>Die Anwendung und Nutzung von Normen ben\u00f6tigt bisher viele manuelle Einzelschritte. Die Informationen aus der entsprechenden Norm m\u00fcssen dabei weitestgehend von Menschen erfasst, extrahiert und in andere Systeme \u00fcbertragen werden. Dabei m\u00fcssen viele Dokumente recherchiert, beschafft und gelesen werden. Au\u00dferdem m\u00fcssen die Mitarbeiter einsch\u00e4tzen, welche Normen und Informationen speziell f\u00fcr das jeweilige Unternehmen und Produkt relevant sind. Hinter und zwischen jedem dieser genannten Prozessschritte steht zudem das Risiko eines Informations\u00fcbertragungsfehlers, der die gesamte Prozesskette und damit ein Produkt in all seinen Facetten (Safety, Security, Performance, Kosten und damit Marktakzeptanz) betreffen kann.<\/p>\n<h4>Beispiel Produktentwicklung in mittelst\u00e4ndischem Betrieb<\/h4>\n<p>Dieser Aufwand l\u00e4sst sich kosteneffektiv verringern, wenn die Bereitstellung und Anwendungsunterst\u00fctzung von Normen durch digitale Services erfolgt, die SMART Standards voraussetzen. Unter anderem k\u00f6nnen Prozessdurchlaufzeiten verk\u00fcrzt und die Rechtssicherheit in der Normenanwendung des Unternehmens verbessert werden, indem IT-gest\u00fctzt die Vollst\u00e4ndigkeit, Aktualit\u00e4t, Richtigkeit, Redundanzfreiheit und Konformit\u00e4t der Normenanwendung sichergestellt wird. Das zeigen die Expertinnen und Experten von DIN und DKE exemplarisch am Beispiel der Produktentwicklung in einem mittelst\u00e4ndischen Maschinenbaubetrieb.<\/p>\n<p>In den betrachteten Szenarien k\u00f6nnen mit SMART Standards bei gleichem Personaleinsatz zwischen 50 und fast 100 Prozent mehr Auftr\u00e4ge bearbeitet werden. Bei den Kosten wird deutlich, welches Volumen an Personal- und Sachkosten im Unternehmen j\u00e4hrlich mit dem Thema Normenanwendung verbunden sein kann und dass mit einer Transformation eine j\u00e4hrliche Kostenreduktion zwischen knapp 50 und rund 65 Prozent m\u00f6glich w\u00e4re. Zudem liegt die Umsatzsteigerung zwischen 32 und 60 Prozent.<\/p>\n<p>DKE-Gesch\u00e4ftsf\u00fchrer Michael Teigeler: &#8222;Mit dem jetzt vorgelegten Whitepaper zeigen wir, dass sich SMART Standards letztlich auch betriebswirtschaftlich f\u00fcr ein Unternehmen auszahlen. Damit werden Normen vom Management nicht mehr nur als Kostenfaktor wahrgenommen. Sie sind ein entscheidender Wettbewerbsvorteil und Innovationstreiber. SMART Standards tragen dazu bei, den Standort Deutschland zu st\u00e4rken.\u201c<\/p>\n<p>Christoph Winterhalter, CEO von DIN: \u201eIn unserem Whitepaper wird zum ersten Mal \u00fcberhaupt untersucht, in welchem Umfang Unternehmen durch eine digitale Bereitstellung von Normeninhalten einen betriebswirtschaftlichen Nutzen haben \u2013 nicht nur qualitativ, sondern quantitativ. Dies ist ein Indikator daf\u00fcr, wie sehr sich eine Investition in die Digitale Infrastruktur von Unternehmen lohnt, mit der das Potential f\u00fcr die Nutzung von Normen noch erheblich gesteigert werden kann.\u201c<br \/>\nDas IDiS-Whitepaper 3 Der betriebswirtschaftliche Nutzen von SMART Standards in Normenanwendungsprozessen steht <a href=\"https:\/\/u7061146.ct.sendgrid.net\/ls\/click?upn=u001.gqh-2BaxUzlo7XKIuSly0rC6GChDrFJOoAT8gDEIoRzkzECLGccMk2qCxIRsqt-2Bb-2BUqN7YsQ-2Fso7fp6-2F5QEmaMNw-3D-3DWnH1_uoJNvF-2FASjth9StXKTRb2IYuGpSKiJriz9IfcpYdIEiJcc6kTbT0QFRxMQq-2BllqtEhJk78wo8oG5JhH1mHHg8P4cXcwoChKG6-2F77y8xtHX7IQpEfrJUDFxdwZygSbjMJ7jqYdbLFM4LDItrgX3C9x7K0kju-2BuWn0W8BF0dAQB2VFTU2vW21OzH5r6RJSTW-2FgdxEQJ2tDIiu7feS8qy-2F98rKyg6soEVx7vmDvNrwGZ3MDV0mG-2FcANUPLmYChuM-2FZ8zkmEK81jgOC9WMFbE1PMNi3xvCTQPJzw0tuxIYNDFcwYv0NFfvSBrRJiWjj5E2CRWRXOeM-2Fsxs9xfBCr1OJAa6-2F8m7kcPcEu3lwqGzo65SI-3D\">hier zum Download<\/a> zur Verf\u00fcgung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Einsatz von SMART Standards besitzt das Potenzial, den Umsatz eines Unternehmens um bis 60 Prozent zu steigern \u2013 der Digitalisierungsgrad der Unternehmen sowie der bereitgestellten Normen spielen dabei die entscheidende Rolle. Das haben DIN und DKE jetzt im Rahmen der Initiative Digitale Standards (IDiS) ermittelt. Untersucht wurde, wie sich der Einsatz von SMART Standards [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,10],"tags":[],"class_list":["post-1015","post","type-post","status-publish","format-standard","hentry","category-firmen-news","category-recht-gesetz"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=1015"}],"version-history":[{"count":1,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1015\/revisions"}],"predecessor-version":[{"id":1016,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1015\/revisions\/1016"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=1015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=1015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=1015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}