{"id":1036,"date":"2024-05-10T11:09:25","date_gmt":"2024-05-10T09:09:25","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/?p=1036"},"modified":"2024-05-10T11:09:25","modified_gmt":"2024-05-10T09:09:25","slug":"dampsoft-und-telekom-krempeln-markt-fuer-praxis-software-um","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2024\/05\/10\/dampsoft-und-telekom-krempeln-markt-fuer-praxis-software-um\/","title":{"rendered":"Dampsoft und Telekom krempeln Markt f\u00fcr Praxis-Software um"},"content":{"rendered":"<p>Die Cloud krempelt den Markt f\u00fcr Praxissoftware weiter um. F\u00fcr ein Ausrufezeichen sorgt aktuell Dampsoft. Das Unternehmen bietet Zahn\u00e4rzten seine Praxis-Verwaltungs-Software (PVS) k\u00fcnftig auch aus der Wolke an. Den Cloud-Auftrag erhielt T-Systems.<\/p>\n<p>Dampsoft ist die PVS-Nr. 1 in der Dental-Branche. Der strategische Zug des Marktf\u00fchrers gilt daher als wegweisend f\u00fcr den gesamten IT-Markt Gesundheit. Hersteller installieren ihre Software traditionell allein auf Praxisrechnern. Auch Dampsoft beh\u00e4lt die Klassik bei. Gleichzeitig er\u00f6ffnet das Unternehmen Praxen aber mit einem neuen Cloud-Produkt viele Vorteile.<\/p>\n<p>Dr. Andrej Teterin, Gesch\u00e4ftsbereichsleiter Produktmanagement &amp; e-health der DAMPSOFT GmbH, sagt: \u201eWeniger Handarbeit am Computer, mehr praktische Funktionen f\u00fcr die Verwaltung und vor allem mehr Zeit f\u00fcr die Patienten. Das steht auf der Wunschliste von Zahn\u00e4rzten ganz oben. Mitarbeiter wissen, wo jeden Tag nervige Computer-Zeit vergeht. Praxen fragen daher immer h\u00e4ufiger nach Cloud-Software. Der Betrieb wird effizienter und gewinnt neue M\u00f6glichkeiten \u2013 genauso f\u00fcr den Patienten. Allein bei der Terminvergabe. Wir bieten unsere Software DS4 daher als Cloud- und gleichzeitig klassische L\u00f6sung an. Das machen im Markt derzeit nur wir. Der Cloud geh\u00f6rt aber ganz klar die Zukunft.\u201c<\/p>\n<h4>Land-\u00c4rzten mit Cloud Verwaltungslast von den Schultern nehmen<\/h4>\n<p>Telekom-Gesundheitschef Gottfried Ludewig sagt: \u201eDemographie fordert die medizinische Versorgung in Deutschland heraus. Besonders auf dem Land, je d\u00fcnner besiedelt umso mehr. Jeder Vierte ist dort \u00dc65. Dort leben auch mehr Hochbetagte \u00e4lter 85. Mehr \u00c4rzte f\u00fcrs Land: Damit ist leider trotz politischer Anreize nicht zu rechnen. Daher m\u00fcssen wir Praxen mit Cloud-Technik maximal bei der Verwaltung entlasten.\u201c<\/p>\n<h4>Praxissoftware \u2013 Wollmilchsau f\u00fcr den Patienten<\/h4>\n<p>Wenigen Patienten ist bewusst, was eine Praxis-Software f\u00fcr sie leistet: Sie sogt f\u00fcr den dringenden Termin, l\u00e4dt ein, erinnert, sagt ab. Sie speichert hochsicher Befunde, verordnete Therapien oder Pillen. Sie sorgt f\u00fcr Rezepte oder rechnet die Kosten ab \u2013 und und und. Umso wichtiger, dass Praxismitarbeiter daf\u00fcr m\u00f6glichst wenige Klicks oder gar keine Maus brauchen. Moderne Software kann das &#8211; aus der Cloud aber leichter und sicherer:<\/p>\n<p>Praxismitarbeiter*innen k\u00f6nnen die Software bequemer von zuhause aus bedienen. \u00dcber PC, Tablet oder Laptop. Vorteilhaft besonders in einer Pandemie. Cloud-Software automatisiert und beschleunigt Verwaltungsarbeiten f\u00fcr das Praxis-Team. Das spart Zeit und Kosten.<\/p>\n<p>Durch die Cloud f\u00e4llt Infrastruktur vor Ort weg. In der Cloud ist die Wartung der Software auch einfacher. Neue Programmversionen spielen die Firmen noch oft f\u00fcr jeden Rechner einzeln und per Hand ein. Die Cloud betankt jeden Praxisrechner dagegen automatisch mit dem aktuellen Release \u2013 beides spart.\u00a0Programmwartung fordert vor allem die Sicherheit. Ein Software-Hack ist der GAU f\u00fcr jeden Praxisinhaber und seine IT-Dienstleister. Das Dilemma: Keine Software ist garantiert l\u00fcckenlos. Und eine ganze Hacker-Szene sucht gezielt nach Fenstern zum Einsteigen. Der Angreifer bestimmt Zeit, Ziel und Einbruchswerkzeug. Im Hase- und Igel-Spiel hat die Praxis aber eine Trumpfkarte: Schnelles Patchen.<\/p>\n<p>Mit Millionen Zeilen Programm-Code k\u00f6nnen Hersteller Sicherheits-L\u00fccken in Software nicht v\u00f6llig ausschlie\u00dfen. Daher durchleuchten sie ihre Produkte regelm\u00e4\u00dfig selbst und warnen Kunden. Finden sie eine L\u00fccke, empfehlen sie den Anwendern einen \u201epatch\u201c \u2013 zu Deutsch Pflaster. Die Arztpraxis klebt mit dem Software-Update die m\u00f6gliche Daten-Wunde zu, bevor ein Angreifer sie ausnutzt.<\/p>\n<p>Hier kommt der Cloud-Vorteil: Der Hersteller stellt das Pflaster zentral in der Cloud bereit und spielt es f\u00fcr alle Kunden gleichzeitig und automatisch auf die angeschlossenen Arzt-Computer. \u201aUngepatchte\u2018 Computer gelten allgemein als leichte Beute.<\/p>\n<p>DS4 ist \u00fcberall verf\u00fcgbar, wo es Internet gibt. Mitarbeiter loggen sich einfach \u00fcber einen Webbrowser ein. Und nutzen das Programm mobil mit verschiedenen Ger\u00e4ten aus Praxis oder Homeoffice. In der Cloud k\u00f6nnen Mitarbeiter gemeinsam zeitgleich an Dokumenten arbeiten. Die Software unterst\u00fctzt Windows, macOS, Linux oder Android. Weitere Informationen finden Sie hier: https:\/\/www.dampsoft.de\/ds4\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Cloud krempelt den Markt f\u00fcr Praxissoftware weiter um. F\u00fcr ein Ausrufezeichen sorgt aktuell Dampsoft. Das Unternehmen bietet Zahn\u00e4rzten seine Praxis-Verwaltungs-Software (PVS) k\u00fcnftig auch aus der Wolke an. Den Cloud-Auftrag erhielt T-Systems. Dampsoft ist die PVS-Nr. 1 in der Dental-Branche. Der strategische Zug des Marktf\u00fchrers gilt daher als wegweisend f\u00fcr den gesamten IT-Markt Gesundheit. Hersteller [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,12,11],"tags":[],"class_list":["post-1036","post","type-post","status-publish","format-standard","hentry","category-firmen-news","category-pc-software","category-security"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=1036"}],"version-history":[{"count":1,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1036\/revisions"}],"predecessor-version":[{"id":1037,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1036\/revisions\/1037"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=1036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=1036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=1036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}