{"id":1315,"date":"2024-11-19T19:23:05","date_gmt":"2024-11-19T18:23:05","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/?p=1315"},"modified":"2024-11-19T19:57:59","modified_gmt":"2024-11-19T18:57:59","slug":"nesic-waehlt-cloudbrink-sase-zur-bereitstellung-von-managed-services","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2024\/11\/19\/nesic-waehlt-cloudbrink-sase-zur-bereitstellung-von-managed-services\/","title":{"rendered":"NESIC w\u00e4hlt Cloudbrink SASE zur Bereitstellung von Managed Services"},"content":{"rendered":"<p>Der japanische Systemintegrator NEC Networks &amp; System Integration Corporation (NESIC) wird k\u00fcnftig den Personal SASE Service von Cloudbrink als Grundlage f\u00fcr sein Virtual Trusted Overlay Network nutzen. Zudem wird Fujitsu ab Januar 2025 auf dem NESIC Virtual Trusted Overlay Network basierende Dienste als Teil der Symphonict-Cloud-Service-Infrastruktur des Unternehmens anbieten.<\/p>\n<p>Das Virtual Trusted Overlay Network erm\u00f6glicht ein hochleistungsf\u00e4higes Zero-Trust-Networking unter Verwendung des Global Edge Mesh von Cloudbrink mit extrem niedrigen Latenzzeiten. NESIC integriert auch andere Dienste wie Endpunktsicherheit und Identit\u00e4tsmanagement, so dass beschleunigte Konnektivit\u00e4t und Sicherheit in einem vollst\u00e4ndig verwalteten Dienst zusammengef\u00fchrt werden k\u00f6nnen.<\/p>\n<p>NESIC entschied sich f\u00fcr die Technologie von Cloudbrink aufgrund ihrer Leistungsf\u00e4higkeit, der integrierten Sicherheit und der einfachen Bereitstellung und Verwaltung sowie aufgrund der Bereitschaft, an der Entwicklung des NESIC-Dienstes mitzuarbeiten.<\/p>\n<p>Osamu Kikuchi, Senior Vice President der NEC Networks &amp; System Integration Corporation, kommentierte: \u201eUnsere Partnerschaft mit Cloudbrink begann vor \u00fcber einem Jahr, und wir haben ihren preisgekr\u00f6nten Service erfolgreich bei Unternehmen auf dem japanischen Markt eingef\u00fchrt. Wir freuen uns darauf, mit diesem neuen Service die traditionelle Netzwerk- und Sicherheitsarchitektur von Unternehmen zu ver\u00e4ndern und unseren Kunden und Partnern weltweit mehr Sicherheit, Einfachheit und Geschwindigkeit zu bieten.\u201c<\/p>\n<p>Der Schl\u00fcssel zum Virtual Trusted Overlay Network ist die F\u00e4higkeit, einen extrem leistungsstarken und sicheren Netzwerkzugang zu bieten. Unabh\u00e4ngige Tests haben die Angabe von Cloudbrink best\u00e4tigt, dass Anwendungen f\u00fcr mobile und Remote-Benutzer mit Breitband- und Drahtlosverbindungen der Verbraucherklasse um das 30-fache beschleunigt werden k\u00f6nnen, ohne dass zus\u00e4tzliche Kosten oder betriebliche Probleme durch die Installation von zus\u00e4tzlicher Hardware entstehen.<\/p>\n<p>Routing- und fortschrittliche Sicherheitsfunktionen werden von einem globalen Netzwerk virtueller PoPs, den so genannten FAST-Edges, bereitgestellt, die mithilfe von KI den n\u00e4chstgelegenen Zugangspunkt ausfindig machen &#8211; in der Regel in weniger als 10 ms.<\/p>\n<p>Prakash Mana, CEO von Cloudbrink, erl\u00e4utert: \u201eWir f\u00fchlen uns geehrt, eine wichtige Rolle beim Virtual Trusted Overlay Network zu spielen. NEC ist ein weltweit anerkannter Partner, und wir teilen die gleiche Vision, SASE f\u00fcr alle nutzbar zu machen &#8211; weniger Verwaltungsaufwand f\u00fcr die Netzwerk- und Sicherheitsteams, ein besseres Erlebnis f\u00fcr die Endnutzer und ein besserer Wert f\u00fcr das Unternehmen.\u201c<\/p>\n<p>NESIC, eine Tochtergesellschaft von Japans f\u00fchrendem Anbieter von Cloud Computing und Netzwerkdiensten NEC Corporation, unterzeichnete Anfang 2023 einen Vertrag als Reseller des Cloudbrink-Dienstes und wurde sp\u00e4ter Designpartner f\u00fcr die Entwicklung des Virtual Trusted Overlay Network.<\/p>\n<p>Weitere Informationen: <a href=\"http:\/\/www.cloudbrink.com\/\" target=\"_blank\" rel=\"noopener\">Cloudbrink<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der japanische Systemintegrator NEC Networks &amp; System Integration Corporation (NESIC) wird k\u00fcnftig den Personal SASE Service von Cloudbrink als Grundlage f\u00fcr sein Virtual Trusted Overlay Network nutzen. Zudem wird Fujitsu ab Januar 2025 auf dem NESIC Virtual Trusted Overlay Network basierende Dienste als Teil der Symphonict-Cloud-Service-Infrastruktur des Unternehmens anbieten. Das Virtual Trusted Overlay Network erm\u00f6glicht [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,5,11],"tags":[],"class_list":["post-1315","post","type-post","status-publish","format-standard","hentry","category-firmen-news","category-networks","category-security"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=1315"}],"version-history":[{"count":1,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1315\/revisions"}],"predecessor-version":[{"id":1316,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1315\/revisions\/1316"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=1315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=1315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=1315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}