{"id":1357,"date":"2024-12-06T12:23:23","date_gmt":"2024-12-06T11:23:23","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/?p=1357"},"modified":"2024-12-06T12:23:23","modified_gmt":"2024-12-06T11:23:23","slug":"controlware-unterstuetzt-public-sector-bei-der-digitalisierung-mit-eigener-business-unit","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2024\/12\/06\/controlware-unterstuetzt-public-sector-bei-der-digitalisierung-mit-eigener-business-unit\/","title":{"rendered":"Controlware unterst\u00fctzt Public Sector bei der Digitalisierung mit eigener Business Unit"},"content":{"rendered":"<p>Die digitale Transformation nimmt auch im Public Sector zunehmend Fahrt auf. Einrichtungen der \u00f6ffentlichen Hand stehen damit vor der Herausforderung, anspruchsvolle Digitalisierungsma\u00dfnahmen Compliance-konform, effizient und sicher umzusetzen. Controlware ber\u00e4t und unterst\u00fctzt Kunden im \u00f6ffentlichen Sektor mit einer eigenen Business Unit.<\/p>\n<p>Einrichtungen der \u00f6ffentlichen Hand stehen bei der Digitalisierung vor zahlreichen Herausforderungen: Viele Beh\u00f6rden arbeiten nach wie vor mit veralteten Legacy-Systemen, haben mit knappen Etats und d\u00fcnnen Personaldecken zu k\u00e4mpfen oder m\u00fcssen bei der Verarbeitung hochgradig sensibler B\u00fcrgerdaten strenge Compliance-Vorgaben einhalten. Um diesen Anforderungen optimal Rechnung zu tragen, hat Controlware die \u00fcberregionale Business Unit \u201ePublic Sector\u201c ins Leben gerufen. Das schlagkr\u00e4ftige Team mit eigenen Strukturen und Zust\u00e4ndigkeiten steht Kommunen, Landes- und Bundesbeh\u00f6rden, aber auch Einrichtungen im Bereich Innere Sicherheit sowie Dienstleistern von Bund und L\u00e4ndern als kompetenter Ansprechpartner f\u00fcr alle Digitalisierungsfragen zur Seite \u2013 von der Ausschreibung bis zur Umsetzung.<\/p>\n<p>In der neuen Business Unit (BU) b\u00fcndelt der IT-Dienstleister und Managed Service Provider das Know-how und die Beratungskompetenz seiner regionalen Public-Sector-Experten, die deutschlandweit bereits zahlreiche anspruchsvolle Digitalisierungsprojekte f\u00fcr \u00f6ffentliche Auftraggeber umgesetzt haben. Das Team \u201ePublic Sector\u201c kann somit auf bew\u00e4hrte Best Practices und konkrete Umsetzungserfahrungen zugreifen und ist aktuell mit rund 30 Prozent am Controlware Umsatz beteiligt. Eine wichtige St\u00e4rke sind auch die engen, oft langj\u00e4hrigen Partnerschaften zu den f\u00fchrenden Technik-Herstellern, deren Produkte und L\u00f6sungen passgenau auf den Einsatz im Public Sector zugeschnitten sind. Das Portfolio soll dabei k\u00fcnftig eigenverantwortlich erweitert und vertieft werden.<\/p>\n<p>\u201eViele Einrichtungen der \u00f6ffentlichen Hand tun sich bei der Modernisierung und der Absicherung ihrer Infrastrukturen bislang schwer \u2013 aber mit dem richtigen Partner an ihrer Seite sind die Herausforderungen l\u00f6sbar\u201c, betont Dirk Schl\u00f6sser, Director Sales Public bei Controlware. \u201eUnser Team spricht die Sprache der Kunden und vereint die hohe Agilit\u00e4t und Geschwindigkeit der Privatwirtschaft mit tiefem Fachwissen aus unseren Projekten f\u00fcr den Public Sector. Damit sind wir f\u00fcr Bund, L\u00e4nder und Kommunen der perfekte Partner f\u00fcr die Umsetzung nachhaltiger, effizienter und effektiver Projekte, die in innovative und langfristige Digitalisierungsstrategien eingebettet sind.\u201c<\/p>\n<p>Sandra Saidowski, Business Development Manager Public bei Controlware, erg\u00e4nzt: \u201eKunden aus dem Public Sector haben ganz andere Anforderungen an Dienstleistungen und Produkte als Unternehmen aus der Privatwirtschaft \u2013 wollen letztlich aber die gleichen Digitalisierungspotenziale erschlie\u00dfen. Um die spezifischen Use Cases in Einrichtungen der \u00f6ffentlichen Hand optimal abbilden zu k\u00f6nnen, haben wir unser Business Development um eine dedizierte Schnittstelle zum Public Sector Team erweitert und so alle Weichen f\u00fcr die Entwicklung ma\u00dfgeschneiderter, bereichs\u00fcbergreifender L\u00f6sungen gestellt.\u201c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die digitale Transformation nimmt auch im Public Sector zunehmend Fahrt auf. Einrichtungen der \u00f6ffentlichen Hand stehen damit vor der Herausforderung, anspruchsvolle Digitalisierungsma\u00dfnahmen Compliance-konform, effizient und sicher umzusetzen. Controlware ber\u00e4t und unterst\u00fctzt Kunden im \u00f6ffentlichen Sektor mit einer eigenen Business Unit. Einrichtungen der \u00f6ffentlichen Hand stehen bei der Digitalisierung vor zahlreichen Herausforderungen: Viele Beh\u00f6rden arbeiten nach [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1357","post","type-post","status-publish","format-standard","hentry","category-firmen-news"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=1357"}],"version-history":[{"count":1,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1357\/revisions"}],"predecessor-version":[{"id":1358,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1357\/revisions\/1358"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=1357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=1357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=1357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}