{"id":1388,"date":"2025-01-09T15:15:53","date_gmt":"2025-01-09T14:15:53","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/?p=1388"},"modified":"2025-01-09T15:15:53","modified_gmt":"2025-01-09T14:15:53","slug":"fortschritt-bei-der-zertifizierung-der-funktionalen-sicherheit-fuer-das-red-hat-in-vehicle-operating-system","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2025\/01\/09\/fortschritt-bei-der-zertifizierung-der-funktionalen-sicherheit-fuer-das-red-hat-in-vehicle-operating-system\/","title":{"rendered":"Fortschritt bei der Zertifizierung der funktionalen Sicherheit f\u00fcr das Red Hat In-Vehicle Operating System"},"content":{"rendered":"<p>Red Hat, Anbieter von Open-Source-L\u00f6sungen, gab bekannt, dass das Unternehmen die Zertifizierung f\u00fcr funktionale Sicherheit in Mixed-Criticality-Umgebungen erhalten hat, einer Schl\u00fcsselgruppe von Subsystemen innerhalb des Red Hat In-Vehicle Operating System. Dies ist ein weiterer wichtiger Schritt auf dem Weg zur ISO-26262-Zertifizierung der funktionalen Sicherheit des Betriebssystems gem\u00e4\u00df der ASIL-B-Klassifizierung (Automotive Safety Integrity Level B). Dieser neue Meilenstein unterstreicht das Engagement von Red Hat, innovative und native Linux-Funktionssicherheit f\u00fcr Kraftfahrzeuge bereitzustellen.<\/p>\n<p>Die gemischte Kritikalit\u00e4t demonstriert die F\u00e4higkeit der Plattform, ASIL-B-Anwendungen neben Qualit\u00e4tsmanagement-Software (QM) auf einem einzigen System-on-Chip (SoC) und einem einzigen Betriebssystem auszuf\u00fchren. Dieser Durchbruch wird durch den Nachweis von \u201eFreedom From Interference\u201c (FFI) \u00fcber alle Schichten des Betriebssystems hinweg erm\u00f6glicht und schafft die Voraussetzungen f\u00fcr eine einfache Integration von sicherheitskritischen und nicht-sicherheitsrelevanten Anwendungen in Automobilsystemen der n\u00e4chsten Generation.<\/p>\n<p>In Zusammenarbeit mit exida hat Red Hat einen neuartigen Ansatz entwickelt und validiert, um die Vorgaben funktionaler Sicherheitsstandards, einschlie\u00dflich ISO 26262, zu erf\u00fcllen und die Herausforderungen zu \u00fcberwinden, die mit komplexer, bereits existierender Open-Source-Software verbunden sind.<\/p>\n<p>Nachdem Red Hat bekannt gegeben hat, dass die Linux Math Library, eine Kernkomponente des Red Hat In-Vehicle Operating System, von exida die ISO-26262-ASIL-B-Zertifizierung f\u00fcr funktionale Sicherheit erhalten hat, ist dies ein weiterer wichtiger Meilenstein, der das Vertrauen in Linux als zukunftsf\u00e4hige Plattform f\u00fcr sicherheitsrelevante Automobilanwendungen st\u00e4rkt. Red Hat hat gezeigt, dass die erforderliche Konfiguration mit gemischter Kritikalit\u00e4t die ASIL-B-Anforderungen zuverl\u00e4ssig erf\u00fcllen kann. Die Zertifizierung tr\u00e4gt nicht nur dazu bei, die Sicherheit des Red Hat In-Vehicle Operating System zu untermauern, sondern bietet Unternehmen auch einen klaren Ansatz, um es vertrauensvoll in zuk\u00fcnftigen Automobilsystemen einzusetzen.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Red Hat, Anbieter von Open-Source-L\u00f6sungen, gab bekannt, dass das Unternehmen die Zertifizierung f\u00fcr funktionale Sicherheit in Mixed-Criticality-Umgebungen erhalten hat, einer Schl\u00fcsselgruppe von Subsystemen innerhalb des Red Hat In-Vehicle Operating System. Dies ist ein weiterer wichtiger Schritt auf dem Weg zur ISO-26262-Zertifizierung der funktionalen Sicherheit des Betriebssystems gem\u00e4\u00df der ASIL-B-Klassifizierung (Automotive Safety Integrity Level B). Dieser [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,12,11],"tags":[],"class_list":["post-1388","post","type-post","status-publish","format-standard","hentry","category-firmen-news","category-pc-software","category-security"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=1388"}],"version-history":[{"count":1,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1388\/revisions"}],"predecessor-version":[{"id":1389,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1388\/revisions\/1389"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=1388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=1388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=1388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}