{"id":1390,"date":"2025-01-13T11:09:58","date_gmt":"2025-01-13T10:09:58","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/?p=1390"},"modified":"2025-01-13T11:09:58","modified_gmt":"2025-01-13T10:09:58","slug":"global-technology-industry-association-gtia-startet-mit-neuem-namen-und-fokus-auf-den-it-channel","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2025\/01\/13\/global-technology-industry-association-gtia-startet-mit-neuem-namen-und-fokus-auf-den-it-channel\/","title":{"rendered":"Global Technology Industry Association (GTIA) startet mit neuem Namen und Fokus auf den IT-Channel"},"content":{"rendered":"<p>Die Global Technology Industry Association (GTIA), bisher bekannt als CompTIA Community, hat heute ihren neuen Namen ver\u00f6ffentlicht. Die GTIA richtet sich ausschlie\u00dflich an den IT-Channel und an IT-Fachkr\u00e4fte. Die Umbenennung folgt auf den Verkauf der Marke CompTIA der Computing Technology Industry Association und deren Schulungs- und Zertifizierungsgesch\u00e4fts, das nun als eigenst\u00e4ndiges, gewinnorientiertes Unternehmen unter dem Namen CompTIA firmiert. Der bestehende, auf Mitgliedschaft basierende Verband, der nun als GTIA bekannt ist, wird weiterhin Dienstleistungen f\u00fcr die IT-Industrie erbringen.<\/p>\n<p>GTIA ist die einzige herstellerunabh\u00e4ngige, Non-Profit-Community, die den weltweiten IT-Channel verbindet und vertritt. Auf internationaler Ebene ist die GTIA die Stimme von Zehntausenden von Fachkr\u00e4ften, die bei mehr als 2.000 MSPs, L\u00f6sungsanbietern, Technologieanbietern, Distributoren und anderen Unternehmen besch\u00e4ftigt sind, die den IT-Channel weltweit bilden.\u00a0\u201eWir freuen uns, ein neues Kapitel f\u00fcr unseren Verband aufzuschlagen &#8222;, sagt Tracy Pound, Vorstandsvorsitzende der GTIA. \u201eJetzt, da wir uns ausschlie\u00dflich auf den IT-Channel konzentrieren, k\u00f6nnen wir unseren Mitgliedern noch mehr Vorteile bieten und ein Umfeld schaffen, in dem jeder willkommen ist und wir alle gemeinsam die Zukunft unserer Branche mitgestalten k\u00f6nnen.\u201c<\/p>\n<p>Der Verkauf der Marke CompTIA und der gewinnorientierten Gesch\u00e4ftsaktivit\u00e4ten hat ein betr\u00e4chtliches Stiftungskapital eingebracht, dessen Aussch\u00fcttungen die Betriebskosten der GTIA auf unbestimmte Zeit decken werden. Dadurch k\u00f6nnen die Mitgliedsbeitr\u00e4ge weiterhin subventioniert und erschwinglich gehalten werden. Die Vorteile f\u00fcr die Mitglieder bleiben erhalten, ebenso wie renommierte globale Veranstaltungen wie die ChannelCon-Konferenz. Dank der Stiftung wird die GTIA auch mehr M\u00f6glichkeiten haben, wohlt\u00e4tige Spenden an Organisationen zu vergeben, die wertvolle Arbeit im Technologiebereich leisten und mehr Menschen weltweit in die Technologiebranche bringen.<\/p>\n<p>Die Leitung der GTIA bleibt in den H\u00e4nden des bestehenden Vorstands. Er setzt sich zusammen aus Top-F\u00fchrungskr\u00e4ften und Vordenkern des IT-Channels, sowie dem Chief Operating Officer (COO) Kelly Ricker und dem Chief Community Officer (CCO) MJ Shoer. Ricker und Shoer berichten an den Exekutivausschuss des Vorstands, w\u00e4hrend der Vorstand die Suche nach einem CEO fortsetzt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Global Technology Industry Association (GTIA), bisher bekannt als CompTIA Community, hat heute ihren neuen Namen ver\u00f6ffentlicht. Die GTIA richtet sich ausschlie\u00dflich an den IT-Channel und an IT-Fachkr\u00e4fte. Die Umbenennung folgt auf den Verkauf der Marke CompTIA der Computing Technology Industry Association und deren Schulungs- und Zertifizierungsgesch\u00e4fts, das nun als eigenst\u00e4ndiges, gewinnorientiertes Unternehmen unter dem [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1390","post","type-post","status-publish","format-standard","hentry","category-firmen-news"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=1390"}],"version-history":[{"count":1,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1390\/revisions"}],"predecessor-version":[{"id":1391,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1390\/revisions\/1391"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=1390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=1390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=1390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}