{"id":1410,"date":"2025-01-21T12:18:50","date_gmt":"2025-01-21T11:18:50","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/?p=1410"},"modified":"2025-01-21T12:18:50","modified_gmt":"2025-01-21T11:18:50","slug":"quantentechnik-zukunftstechnik-made-in-germany-bereit-fuer-den-durchbruch","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2025\/01\/21\/quantentechnik-zukunftstechnik-made-in-germany-bereit-fuer-den-durchbruch\/","title":{"rendered":"Quantentechnik \u2013 Zukunftstechnik made in Germany bereit f\u00fcr den Durchbruch"},"content":{"rendered":"<p>Quantentechnik steht an der Schwelle, die digitale Welt zu revolutionieren und bietet Potenzial, Probleme zu l\u00f6sen, die mit herk\u00f6mmlichen Computern nicht bew\u00e4ltigt werden k\u00f6nnen. Deutschland hat sich in den letzten Jahren zunehmend als ein bedeutender Standort f\u00fcr Forschung und Entwicklung auf diesem Gebiet positioniert. Doch kann Deutschland im globalen Wettlauf um die technische Vorherrschaft in der Quantentechnik mithalten? Im folgenden Kommentar beleuchtet Tobias W\u00f6lk, Produktmanager bei reichelt elektronik, wie es um Quantentechnik in der Bundesrepublik steht und ob Deutschland eine Chance hat, sich als Vorreiter dieser Zukunftstechnik zu etablieren.<\/p>\n<h4>Quantentechnik damals und heute<\/h4>\n<p>Als Physikgr\u00f6\u00dfen wie Werner Heisenberg oder Erwin Schr\u00f6dinger vor etwa 100 Jahren die moderne Quantenmechanik aus der Taufe hoben und damit bis dato als selbstverst\u00e4ndlich geglaubte physikalische Gesetzm\u00e4\u00dfigkeiten in Frage stellten, ging nicht nur ein Ruck durch die Welt der Physik, sondern durch die gesamte Gesellschaft. Bis die ersten Produkte und Techniken auf den Markt kamen, die auf neuen Erkenntnissen der Quantentechnik basierten, sollte es aber noch dauern.<\/p>\n<p>Heute erleben wir in Deutschland den Beginn einer neuen Bl\u00fctezeit der Quantentechnik. Die Grundlagenforschung zu Bereichen wie Quantencomputing oder Quantensensorik wird von Universit\u00e4ten und Forschungsinstituten ebenso wie von Unternehmen vorangetrieben. Auf der anderen Seite berichten letztere in einer aktuellen Bitkom-Studie, dass noch unausgereifte Technik, fehlende praktische Anwendungsbereiche sowie ein unklarer wirtschaftlicher Nutzen H\u00fcrden darstellen, um in Quantentechnik zu investieren. In diesem Sinne steht das Land gerade an einem Scheideweg: Von den heute getroffenen Investitionsentscheidungen h\u00e4ngt ab, ob sich die neue Technik in Deutschland etablieren kann, oder ob andere L\u00e4nder eine unantastbare Monopolstellung aufbauen werden.<\/p>\n<p>Die Forschung zu Quantentechniken in Deutschland ist exzellent und wird durch einige Initiativen gef\u00f6rdert. Gerade erst wurde in Frankfurt an der Oder ein Joint Lab f\u00fcr die Forschung an Halbleiterbasiertem Quantencomputing er\u00f6ffnet und ist nur ein Beispiel einer lebendigen Forschungskultur mit dem Schwerpunkt Quantentechnik. Unternehmen investieren ebenfalls in Quantentechnik-Forschung aus Deutschland. So hat IBM Anfang Oktober sein erstes Quanten-Data-Center au\u00dferhalb der USA in Stuttgart er\u00f6ffnet und bietet so die M\u00f6glichkeit, den neuesten IBM-Heron-Quantencomputer zu nutzen und von seiner enormen Leistung und Geschwindigkeit zu profitieren.<\/p>\n<p>Innovative auf Quantentechnik beruhende Produkte wie Flashspeicher und MRT sind bereits auf dem Markt erh\u00e4ltlich und haben sich etabliert. Neue, noch komplexere Produkte wie etwa Quantensensoren sind gerade dabei, den Markt zu erobern. Zwar sch\u00e4tzen Experten oft, dass es noch etwa zehn Jahre dauern wird, bis diese am Markt etabliert werden, jedoch haben erste deutsche Unternehmen bereits bemerkenswerte marktreife Produkte und L\u00f6sungen vorgestellt. So vertreibt reichelt elektronik beispielsweise schon einen der ersten industrietauglichen Quantensensoren der jungen Leipziger Firma Quantum Technologies. Das Produkt bietet zwei entscheidende Vorteile: Es ist deutlich kompakter und robuster als\u00a0vergleichbare Magnetometer und eignet sich so f\u00fcr die Nutzung im Hochspannungsbereich ebenso wie in der Elektromobilit\u00e4t.<\/p>\n<p>Zudem lassen sich auch auf Seiten der Software Fortschritte beobachten. Erste Apps f\u00fcr Quantencomputing konnten bereits ausgerollt werden. Ein Beispiel daf\u00fcr ist die Firma QUTAC, die deutschen Industrieunternehmen hilft, \u00d6kosysteme f\u00fcr Quantentechnik zu errichten und sie so in die Anwendung zu bringen. Derzeit werden diese vor allem genutzt, um die Maschinenbelegung in der Produktion zu optimieren. Die Technik bietet aber noch viel Potential f\u00fcr weitere Anwendungsbereiche. Besonders der deutliche Geschwindigkeitsvorteil, den Quantencomputer gegen\u00fcber herk\u00f6mmlichen Rechnern haben, erm\u00f6glicht, rasch Analysen aus enormen Datenmengen zu erstellen und so effizientere L\u00f6sungen zu finden \u2013 etwa zur Optimierung von Lieferketten oder um mithilfe komplexer Simulationen das Verhalten von Materialien und Werkstoffen \u00fcber eine l\u00e4ngere Nutzungsdauer hinweg zu berechnen. Jedoch sind Qubits noch immer extrem empfindlich gegen\u00fcber \u00e4u\u00dferen Einfl\u00fcssen wie etwa Temperaturschwankungen oder Vibrationen. Diese Herausforderung muss gel\u00f6st werden, damit Quantencomputing sich auch in der Industrie durchsetzen kann.<\/p>\n<h4>Deutschland im hart umk\u00e4mpften Quantenrennen<\/h4>\n<p>Die Chancen, die Quantentechnik in vielen Bereichen \u2013 Entwicklung, Energie, Lieferketten, E-Mobility, Medizintechnik, Finanzen, IT-Security und Kryptographie und viele mehr \u2013 mit sich bringen, sind enorm. Besonders in Zusammenspiel mit KI und Datenwissenschaften wird sie der Industrie zu gro\u00dfen Entwicklungssch\u00fcben verhelfen.<\/p>\n<p>Deshalb ist Deutschland auch nicht das einzige Land, das auf Quantentechnik setzt. L\u00e4ngst sind die USA und China mit gro\u00dfen Investitionen vorangeschritten und f\u00fchren das Quantenrennen an. Und auch Japan hat laut Expertenmeinungen derzeit noch besser ausgereifte L\u00f6sungen und Produkte. Besonders zu nennen ist hier zum Beispiel die St\u00e4rke des japanischen Unternehmens Fujitsu und das Forschungsinstitut Riken im Bereich Quantencomputing. Fujitsu hat mit Digital Annealer eine Technik entwickelt, die auf Quantencomputing beruht, um komplexe Optimierungsprobleme schneller zu l\u00f6sen. Die Konkurrenz ist also stark.<\/p>\n<p>Das bedeutet jedoch nicht, dass die W\u00fcrfel schon gefallen sind. Deutschland hat noch immer gute Chancen, sich als wichtiger Player auf diesem neu entstehenden Markt zu positionieren. Laut der bereits zitierten Bitkom-Studie sch\u00e4tzen sich deutsche Entwickler und Anwender von Quantentechniken selbst als Vorreiter in diesem Bereich ein. Die Konkurrenz sollte deshalb als Herausforderung und Chance gleichzeitig verstanden werden.<\/p>\n<p>Deutschland hat die einmalige Chance, einen neuen Industriezweig aufzubauen und dort eine wichtige Position auf dem Weltmarkt einzunehmen. Und daf\u00fcr hat das Land die besten Voraussetzungen, denn gebraucht wird vor allem ein dynamisches und gut ausgebautes \u00d6kosystem, das neugierig auf Quantentechnik ist und Anwendungen in der Praxis schafft. Deutschland hat einen Reichtum an Unternehmen, die technisch fortgeschritten genug sind, um diesen Schritt zu wagen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quantentechnik steht an der Schwelle, die digitale Welt zu revolutionieren und bietet Potenzial, Probleme zu l\u00f6sen, die mit herk\u00f6mmlichen Computern nicht bew\u00e4ltigt werden k\u00f6nnen. Deutschland hat sich in den letzten Jahren zunehmend als ein bedeutender Standort f\u00fcr Forschung und Entwicklung auf diesem Gebiet positioniert. Doch kann Deutschland im globalen Wettlauf um die technische Vorherrschaft in [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,5,12],"tags":[],"class_list":["post-1410","post","type-post","status-publish","format-standard","hentry","category-firmen-news","category-networks","category-pc-software"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=1410"}],"version-history":[{"count":1,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1410\/revisions"}],"predecessor-version":[{"id":1411,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1410\/revisions\/1411"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=1410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=1410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=1410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}