{"id":1420,"date":"2025-01-28T15:23:18","date_gmt":"2025-01-28T14:23:18","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/?p=1420"},"modified":"2025-01-28T15:23:18","modified_gmt":"2025-01-28T14:23:18","slug":"extreme-networks-erstklassige-konnektivitaet-und-analytics-ermoeglichen-sichere-prozesse-an-flughaefen","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2025\/01\/28\/extreme-networks-erstklassige-konnektivitaet-und-analytics-ermoeglichen-sichere-prozesse-an-flughaefen\/","title":{"rendered":"Extreme Networks: Erstklassige Konnektivit\u00e4t und Analytics erm\u00f6glichen sichere Prozesse an Flugh\u00e4fen"},"content":{"rendered":"<p>Extreme Network, Anbieter von KI-gest\u00fctzter Automatisierung f\u00fcr Netze, gibt bekannt, dass Flugh\u00e4fen weltweit im vergangenen Jahr L\u00f6sungen von Extreme eingesetzt haben, um die Erfahrungen der Reisenden zu verbessern, die Prozesse zu optimieren und die Anforderungen eines rekordverd\u00e4chtigen Jahres f\u00fcr Flugreisen zu erf\u00fcllen. 2024 wurden von der TSA (Transportation Security Administration) in den USA nach eigenen Angaben 904 Millionen Passagiere kontrolliert, was einem Anstieg von mehr als f\u00fcnf Prozent im Vergleich zu 2023 entspricht.<\/p>\n<p>Namhafte Flugh\u00e4fen \u2013 darunter der Charles de Gaulle Airport in Paris, der Charlotte Douglas International Airport, der Harry Reid International Airport, der Ottawa International Airport, der Paris-Orly Airport, der Philadelphia International Airport und der Sharjah International Airport in den Vereinigten Arabischen Emiraten \u2013 verlassen sich auf Extreme Networks, um Konnektivit\u00e4ts- und Analytics-L\u00f6sungen bereitzustellen, mit denen Flugh\u00e4fen und Fluggesellschaften effizienter arbeiten k\u00f6nnen.<\/p>\n<p>Extreme Wi-Fi, Analytics, Fabric und Switching spielen eine entscheidende Rolle im Flughafenbetrieb, da sie ein effizientes Flugmanagement, eine bessere Koordination zwischen den Besch\u00e4ftigten und einen insgesamt verbesserten Ablauf in Bereichen wie Ticketing, Einzelhandel, Anzeigetafeln, Sicherheitskameras und Gep\u00e4ckverfolgung erm\u00f6glichen. Mit Extreme Wi-Fi und Analytics k\u00f6nnen Fluggesellschaften und Flugh\u00e4fen einen besseren Einblick in die Besucherzahlen und Verweilzeiten gewinnen, die Vorlieben der Passagiere im Einzelhandel erkennen und das Personal w\u00e4hrend der Hauptreisezeiten effizienter einsetzen. Dar\u00fcber hinaus erhalten Flugh\u00e4fen mit Extreme Fabric, der sicheren Campus-Fabric-L\u00f6sung f\u00fcr Unternehmen, ein schnelles, effizientes und sicheres Netzwerk, das gro\u00dfen Datenverkehr abwickelt und das Wi-Fi f\u00fcr Flugg\u00e4ste von sensiblen Aktivit\u00e4ten wie der Personalkommunikation trennt.<\/p>\n<p>Paris Charles de Gaulle (CDG) und Paris-Orly (ORY) sind die beiden gr\u00f6\u00dften Flugh\u00e4fen Frankreichs, die beide von der Groupe ADP betrieben werden. Die Flugh\u00e4fen, die in Partnerschaft mit SPIE ICS arbeiten, nutzen die L\u00f6sungen von Extreme Networks \u2013 einschlie\u00dflich Fabric, ExtremeCloud\u2122 IQ und Universal Hardware \u2013 f\u00fcr einen einfachen Tagesbetrieb, nahtlose Konnektivit\u00e4t f\u00fcr Passagiere und Airline-Personal und einfaches Management von Tausenden vernetzter Ger\u00e4te wie Handscanner f\u00fcr Tickets, Ausweiskontrollsysteme und andere Ger\u00e4te, die f\u00fcr ein reibungsloses Reiseerlebnis notwendig sind. Die Flugh\u00e4fen haben vor kurzem eine Netzwerkmodernisierung mit Extreme abgeschlossen, bei der veraltete Switches an 700 technischen Standorten ohne Beeintr\u00e4chtigung des laufenden Flughafenbetriebs ausgetauscht wurden. Die neue Netzwerkinfrastruktur erh\u00f6hte die Bandbreite um das 10- bis 25-fache und erm\u00f6glichte es den Flugh\u00e4fen, technische Prozesse zu standardisieren, was sowohl die Netzwerkleistung als auch die Energieeffizienz deutlich verbessert.<\/p>\n<p>Der Harry Reid International Airport (LAS) setzt auf Extreme Fabric, um den Betrieb des wichtigsten Verkehrsflughafens von Las Vegas und der beiden kleineren Flugh\u00e4fen zu vereinheitlichen und die Arbeitsbelastung des IT-Teams deutlich zu reduzieren. Das Netzwerk unterst\u00fctzt G\u00e4ste-Wi-Fi sowie digitale Annehmlichkeiten wie die Verfolgung von Gep\u00e4ckanh\u00e4ngern und Services an den Airline-Schaltern. Die Fabric erm\u00f6glicht es dem IT-Team, die Konnektivit\u00e4t bei Bedarf f\u00fcr Wartungsarbeiten einfach zu erweitern, um den Passagieren ein nahtloses Erlebnis zu bieten.<\/p>\n<p>Der Philadelphia International Airport (PHL) setzt Extreme Networks f\u00fcr Core Routing Services sowie f\u00fcr die sichere Automatisierung mit Extreme Fabric und Switching ein. Der PHL ist ein gro\u00dfer Flughafen, der seine Terminals aufr\u00fcstet. Das bedeutet, dass das Netzwerkteam flexibel genug sein muss, um neben dem t\u00e4glichen Betrieb f\u00fcr 17.000 Angestellte und 30 Millionen Passagiere j\u00e4hrlich auch Bauprojekte zu unterst\u00fctzen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Extreme Network, Anbieter von KI-gest\u00fctzter Automatisierung f\u00fcr Netze, gibt bekannt, dass Flugh\u00e4fen weltweit im vergangenen Jahr L\u00f6sungen von Extreme eingesetzt haben, um die Erfahrungen der Reisenden zu verbessern, die Prozesse zu optimieren und die Anforderungen eines rekordverd\u00e4chtigen Jahres f\u00fcr Flugreisen zu erf\u00fcllen. 2024 wurden von der TSA (Transportation Security Administration) in den USA nach eigenen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,5,11],"tags":[],"class_list":["post-1420","post","type-post","status-publish","format-standard","hentry","category-firmen-news","category-networks","category-security"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=1420"}],"version-history":[{"count":1,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1420\/revisions"}],"predecessor-version":[{"id":1421,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1420\/revisions\/1421"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=1420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=1420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=1420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}