{"id":1425,"date":"2025-01-29T14:26:00","date_gmt":"2025-01-29T13:26:00","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/?p=1425"},"modified":"2025-01-29T14:26:00","modified_gmt":"2025-01-29T13:26:00","slug":"termine-fuer-die-controlware-it-security-roadshow-2025-stehen-fest","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2025\/01\/29\/termine-fuer-die-controlware-it-security-roadshow-2025-stehen-fest\/","title":{"rendered":"Termine f\u00fcr die Controlware IT-Security Roadshow 2025 stehen fest"},"content":{"rendered":"<p>Controlware geht auf Tour: Im Februar und M\u00e4rz pr\u00e4sentiert der IT-Dienstleister und Managed Service Provider auf der \u201eControlware IT-Security Roadshow 2025\u201c in Meerbusch (20.02.), Frankfurt (25.02.), Berlin (27.02.), Stuttgart (11.03.) und M\u00fcnchen (13.03.) die neuesten Trends und Techniken rund um die Themen Informationssicherheit und Datenschutz.<\/p>\n<p>IT-Security macht auch 2025 Schlagzeilen: Immer \u00f6fter nehmen professionelle Cyberkriminelle und staatliche Akteure Unternehmen bei Hackerangriffen ins Visier und nutzen interne und externe Schwachstellen und kompromittierte Zug\u00e4nge, um Zugang zu wertvollen sensiblen Daten zu erhalten. Gleichzeitig verpflichten neue regulatorische Vorgaben wie NIS2 und DORA die Security-Teams, die Weichen f\u00fcr einen risikobasierten Schutz von Anwendern, Daten und Systemen zu stellen, und r\u00fccken die Resilienz der Netze in den Fokus. \u201eMit der Digitalisierung und Automatisierung der Prozesse gewinnt das Thema Cybersicherheit kontinuierlich an Bedeutung, gestaltet sich durch die wachsenden Angriffsfl\u00e4chen aber auch immer komplexer\u201c, fasst Mario Emig, Head of Information Security Business Development bei Controlware, zusammen. \u201eAuf unserer \u201aControlware IT-Security Roadshow 2025\u2018 geben wir den CISOs und Security-Verantwortlichen einen \u00dcberblick \u00fcber praxisorientierte Sicherheitsstrategien, innovative L\u00f6sungen und zuk\u00fcnftige Trends \u2013 auch mit Blick auf die Anforderungen moderner Cloud-Umgebungen.\u201c<\/p>\n<p>Auf der diesj\u00e4hrigen Roadshow pr\u00e4sentieren die Controlware Experten gemeinsam mit den Partnern Check Point, Cisco, Fortinet, genua, Infoblox, OPSWAT, Palo Alto Networks, SentinelOne, Tenable und Zscaler innovative L\u00f6sungen f\u00fcr den Schutz moderner Cloud-Infrastrukturen. Die Teilnehmer erfahren dabei unter anderem, wie sie durch zeitgem\u00e4\u00dfe Segmentierung effektive Sicherheitszonen schaffen und mit einem ganzheitlichen Exposure Management ihre Schwachstellen wirkungsvoll kontrollieren. Ein Schwerpunkt der Veranstaltungen ist der Einsatz von Automatisierung und DevSecOps, um die Einhaltung der NIS2- und DORA-Anforderungen sicherzustellen. Im Fokus steht dar\u00fcber hinaus der effektive Schutz vor Cybergefahren mit Managed Detection &amp; Response (MDR) und Vulnerability Management Services (VMS) von Controlware.<\/p>\n<p>Auf der begleitenden Partner-Ausstellung haben die Besucher Gelegenheit, sich umfassend \u00fcber die aktuellen L\u00f6sungen und Roadmaps der anwesenden Security-Hersteller zu informieren \u2013 und ihre konkreten Anforderungen zu diskutieren.<\/p>\n<p>Die Termine im \u00dcberblick:<\/p>\n<ul>\n<li>20.02.: Meerbusch \u2013 Gut Dyckhof, Am Dyckhof 3, 40667 Meerbusch<\/li>\n<li>25.02.: Frankfurt \u2013 Klassikstadt, Orber Str. 4a, 60386 Frankfurt<\/li>\n<li>27.02.: Berlin \u2013 Maritim proArte Hotel, Friedrichstra\u00dfe 151, 10117 Berlin<\/li>\n<li>11.03.: Stuttgart \u2013 M\u00f6venpick Hotel Stuttgart Messe &amp; Congress, Flughafenstrasse 43, 70629 Stuttgart<\/li>\n<li>13.03.: M\u00fcnchen \u2013 Jochen Schweizer Arena, Ludwig-B\u00f6lkow-Allee 1, 82024 Taufkirchen<\/li>\n<\/ul>\n<p>Die Teilnahme ist kostenfrei. Aufgrund der begrenzten Teilnehmerzahl wird eine fr\u00fchzeitige Anmeldung unter <a href=\"https:\/\/www.controlware.de\/termine\" target=\"_blank\" rel=\"noopener\">https:\/\/www.controlware.de\/termine<\/a> empfohlen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Controlware geht auf Tour: Im Februar und M\u00e4rz pr\u00e4sentiert der IT-Dienstleister und Managed Service Provider auf der \u201eControlware IT-Security Roadshow 2025\u201c in Meerbusch (20.02.), Frankfurt (25.02.), Berlin (27.02.), Stuttgart (11.03.) und M\u00fcnchen (13.03.) die neuesten Trends und Techniken rund um die Themen Informationssicherheit und Datenschutz. IT-Security macht auch 2025 Schlagzeilen: Immer \u00f6fter nehmen professionelle Cyberkriminelle [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,11],"tags":[],"class_list":["post-1425","post","type-post","status-publish","format-standard","hentry","category-firmen-news","category-security"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=1425"}],"version-history":[{"count":1,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1425\/revisions"}],"predecessor-version":[{"id":1426,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1425\/revisions\/1426"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=1425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=1425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=1425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}