{"id":1484,"date":"2025-03-18T15:34:37","date_gmt":"2025-03-18T14:34:37","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/?p=1484"},"modified":"2025-03-18T15:35:47","modified_gmt":"2025-03-18T14:35:47","slug":"commerz-real-geht-in-die-europaeische-cloud-und-setzt-auf-datensouveraenitaet","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2025\/03\/18\/commerz-real-geht-in-die-europaeische-cloud-und-setzt-auf-datensouveraenitaet\/","title":{"rendered":"Commerz Real geht in die europ\u00e4ische Cloud und setzt auf Datensouver\u00e4nit\u00e4t"},"content":{"rendered":"<p>Die Commerz Real setzt bei ihrer Cloud-Strategie auf Europa: Ein gro\u00dfer Teil der Cloud-Infrastruktur des Assetmanagers der Commerzbank-Gruppe wird in Zukunft beim europ\u00e4ischen Cloud-Anbieter OVHcloud gehostet, der Rechenzentrums- und Cloud-Services in Deutschland und Europa betreibt. Bei der Migration aus dem eigenen On-Premises-Rechenzentrum in die Cloud und der Umsetzung der eigenen Hybrid-Cloud-Strategie unterst\u00fctzen die Experten des IT-Dienstleisters Controlware\/Networkers.<\/p>\n<p>\u201eNeben der Nutzung von Cloud-Services der bekannten US-amerikanischen Anbieter wollen wir bei unserer Hybrid-Cloud-Strategie explizit einen europ\u00e4ischen Anbieter nutzen, um Datensouver\u00e4nit\u00e4t und Made-in-EU sicherzustellen\u201c, sagt Dr. Nikolaus Schmidt, Global Head of Technology &amp; Innovation bei Commerz Real. \u201eOVHcloud und Controlware\/Networkers haben uns mit ihrer L\u00f6sung und dem Transitionskonzept voll und ganz \u00fcberzeugt.\u201c<\/p>\n<p>Die Entscheidung garantiert ein datensouver\u00e4nes Hosting und f\u00e4llt in einen Kontext globaler und politischer Umbr\u00fcche. Als weltweit agierender Assetmanager f\u00fcr Sachwertinvestments in Immobilien und erneuerbare Energien ist die Commerz Real auf eine performante und wirtschaftliche IT-Infrastruktur angewiesen. Insbesondere in der Finanzbranche spielen lokale Datenresidenz, die Sicherheit und Kontrolle \u00fcber die Datenverarbeitung und -speicherung eine zentrale Rolle. Mit der Wahl von OVHcloud stellt das Unternehmen sicher, dass seine Daten in einem genau definierten regulatorischen Rahmen bleiben und die Datenverarbeitung den europ\u00e4ischen Datenschutzbestimmungen entspricht. Zudem werden die IT-L\u00f6sungen vor jeglicher Einsicht oder Einflussnahme, insbesondere aus dem Ausland, gesch\u00fctzt.<\/p>\n<p>Als Finanzdienstleister unterliegt die Commerz Real strengen aufsichtsrechtlichen Vorgaben und muss mit Blick auf den Datenschutz und die Informationssicherheit h\u00f6chsten Standards gerecht werden. Dazu z\u00e4hlen beispielsweise die Datenschutzgrundversordnung (DSGVO) und der Digital Operational Resilience Act (DORA), der Banken und Finanzunternehmen zu operationaler Resilienz verpflichtet, aber auch Sicherheitszertifikate wie die deutsche C5-Zertifizierung des Bundesamts f\u00fcr Sicherheit in der Informationstechnik (BSI), die ISO-Zertifizierungen ISO27001, ISO27017 und ISO27018 und SOC2.<\/p>\n<h4>Verl\u00e4ssliche, souver\u00e4ne Infrastruktur von OVHcloud<\/h4>\n<p>Um auch in der Cloud die durchg\u00e4ngige Einhaltung aller regulatorischen Vorgaben zu gew\u00e4hrleisten, setzte das Projektteam mit OVHcloud auf einen erfahrenen, in der EU ans\u00e4ssigen Hosting-Partner. \u201eDie Entscheidung der Commerz Real f\u00fcr OVHcloud zeigt, dass eine souver\u00e4ne europ\u00e4ische Cloud eine leistungsf\u00e4hige Alternative zu globalen Anbietern darstellt. Gemeinsam mit unseren Partnern bei Controlware\/Networkers haben wir eine sichere, regelkonforme und zukunftsf\u00e4hige Cloud-L\u00f6sung realisiert\u201c, sagt Falk Weinreich, General Manager Central Europe bei OVHcloud.<\/p>\n<p>Mit der Beratung und Umsetzung von Controlware\/Networkers entstanden eine detaillierte Migrationsstrategie und ein Plan f\u00fcr die n\u00e4chsten f\u00fcnf Jahre, mit dem das interne Team der Commerz Real mit ma\u00dfgeschneiderten Managed Services von zeitintensiven Betriebs- und Verwaltungsaufgaben entlastet wird. \u201eAls professioneller Partner f\u00fcr Managed-Services haben wir f\u00fcr die Commerz Real ein sinnvolles Gesamtkonstrukt erstellt und gelangen an ein Ma\u00df an Sicherheit und Betreuung, das Anwenderunternehmen selbst kaum erreichen k\u00f6nnen. Durch unsere Unterst\u00fctzung im Projekt sind f\u00fcr das Team der Commerz Real wertvolle Freir\u00e4ume f\u00fcr eigene Innovationsvorhaben geschaffen worden\u201c, erkl\u00e4rt Peter Schidlo, der das Projekt als Key Account Manager bei Controlware\/Networkers leitet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Commerz Real setzt bei ihrer Cloud-Strategie auf Europa: Ein gro\u00dfer Teil der Cloud-Infrastruktur des Assetmanagers der Commerzbank-Gruppe wird in Zukunft beim europ\u00e4ischen Cloud-Anbieter OVHcloud gehostet, der Rechenzentrums- und Cloud-Services in Deutschland und Europa betreibt. Bei der Migration aus dem eigenen On-Premises-Rechenzentrum in die Cloud und der Umsetzung der eigenen Hybrid-Cloud-Strategie unterst\u00fctzen die Experten des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,5],"tags":[],"class_list":["post-1484","post","type-post","status-publish","format-standard","hentry","category-firmen-news","category-networks"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=1484"}],"version-history":[{"count":1,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1484\/revisions"}],"predecessor-version":[{"id":1485,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1484\/revisions\/1485"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=1484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=1484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=1484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}