{"id":1497,"date":"2025-03-28T09:06:07","date_gmt":"2025-03-28T08:06:07","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/?p=1497"},"modified":"2025-03-28T09:06:07","modified_gmt":"2025-03-28T08:06:07","slug":"deutscher-seniorentag-2025-digitale-absicherung-auch-im-alter","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2025\/03\/28\/deutscher-seniorentag-2025-digitale-absicherung-auch-im-alter\/","title":{"rendered":"Deutscher Seniorentag 2025: Digitale Absicherung auch im Alter"},"content":{"rendered":"<p>Fast jede bzw. jeder F\u00fcnfte (19%) der \u00dcber-69-J\u00e4hrigen war schon einmal von Cyberkriminalit\u00e4t betroffen, zeigt der Cybersicherheitsmonitor des Bundesamts f\u00fcr Sicherheit in der Informationstechnik (BSI). Auch f\u00fcr Seniorinnen und Senioren gilt es daher, sich im digitalen Alltag zu sch\u00fctzen \u2013 ob beim Schreiben von E-Mails oder beim Suchen nach aktuellen Informationen. Das BSI ber\u00e4t sie sowohl mit einem auf die Zielgruppe zugeschnittenen, digitalen Informationsangebot als auch mit einem Messestand beim 14. Deutschen Seniorentag 2025 in Mannheim.<\/p>\n<p>Katja Zierleyn, Expertin f\u00fcr Verbraucherschutz beim BSI: \u201eSpeziell f\u00fcr Seniorinnen und Senioren er\u00f6ffnet die Digitalisierung viele M\u00f6glichkeiten, den Alltag komfortabler zu gestalten und das soziale Miteinander zu erleichtern. Einige sind dabei mit allen Technologien bestens vertraut. F\u00fcr andere ist bereits die sichere Inbetriebnahme eines Smartphones eine Herausforderung. Sowohl Seniorinnen und Senioren als auch Angeh\u00f6rige unterst\u00fctzt das BSI daher bei der Umsetzung eines digitalen Basisschutz. Mein Appell: Sprechen Sie mit Menschen aus ihrem Umfeld \u00fcber IT-Sicherheit \u2013 etwa \u00fcber Phishing-Maschen, die Ihnen bereits begegnet sind. So sch\u00fctzen wir uns gegenseitig.\u201c<\/p>\n<p>Ein wichtiges Thema f\u00fcr Seniorinnen und Senioren ist zudem der digitale Nachlass: Was passiert nach meinem Tod oder etwa im Falle eines Unfalls mit meinen Benutzerkonten, Ger\u00e4ten und Daten? Wer sich fr\u00fchzeitig Gedanken dar\u00fcber macht, verhindert, dass beispielsweise kostenpflichtige Abos weiterlaufen und ver\u00f6ffentlichte Fotos dauerhaft im Netz bleiben. In der M\u00e4rzfolge des BSI-Podcasts \u201eUpdate verf\u00fcgbar\u201c bespricht das Moderatorenduo gemeinsam mit Johannes Diller, Mobilreferent beim Digitalen Engel, was in den digitalen Nachlass geh\u00f6rt, wie ein digitaler Nachlass verwaltet und \u00fcbergeben werden kann und warum nicht nur Seniorinnen und Senioren vorsorgen sollten.<\/p>\n<p>Das BSI ber\u00e4t Verbraucherinnen und Verbraucher zudem vor Ort beim 14. Deutschen Seniorentag, der vom 2. bis 4.4.2025 in Mannheim stattfindet. Am Stand D14 (Ebene 0) k\u00f6nnen sie mit Expertinnen und Experten rund um das Thema Cybersicherheit ins Gespr\u00e4ch kommen. Das BSI l\u00e4dt am Messestand auch gemeinsam mit Guido Steinke von der Verbraucher Initiative e.V. zu \u201eGuidos Mittagstisch mit dem BSI\u201c ein: Am 02.04. von 13.00 &#8211; 13.30 Uhr sowie am 04.04. von 11.30 &#8211; 12.00 Uhr gibt es neben einem Vortrag zum Thema \u201eSicherheit im digitalen Alltag\u201c viel Zeit f\u00fcr Fragen.<\/p>\n<p>Verbraucherinnen und Verbraucher, die nicht vor Ort in Mannheim sein k\u00f6nnen, finden Handlungsempfehlungen im <a href=\"https:\/\/www.bsi.bund.de\/SharedDocs\/Downloads\/DE\/BSI\/Publikationen\/Broschueren\/Wegweiser_Checklisten_Flyer\/Brosch_A6_Surfen_aber_sicher.pdf?__blob=publicationFile&amp;v=15\">\u201eWegweiser f\u00fcr den digitalen Alltag: Das Internet sicher nutzen\u201c<\/a> sowie auf der <a href=\"https:\/\/www.bsi.bund.de\/DE\/Themen\/Verbraucherinnen-und-Verbraucher\/Informationen-und-Empfehlungen\/Cyber-Sicherheitsempfehlungen\/cyber-sicherheitsempfehlungen_node.html\" target=\"_blank\" rel=\"noopener\">Webseite des BSI<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fast jede bzw. jeder F\u00fcnfte (19%) der \u00dcber-69-J\u00e4hrigen war schon einmal von Cyberkriminalit\u00e4t betroffen, zeigt der Cybersicherheitsmonitor des Bundesamts f\u00fcr Sicherheit in der Informationstechnik (BSI). Auch f\u00fcr Seniorinnen und Senioren gilt es daher, sich im digitalen Alltag zu sch\u00fctzen \u2013 ob beim Schreiben von E-Mails oder beim Suchen nach aktuellen Informationen. Das BSI ber\u00e4t sie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,11,4],"tags":[],"class_list":["post-1497","post","type-post","status-publish","format-standard","hentry","category-recht-gesetz","category-security","category-telecom"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=1497"}],"version-history":[{"count":1,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1497\/revisions"}],"predecessor-version":[{"id":1498,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1497\/revisions\/1498"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=1497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=1497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=1497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}