{"id":1581,"date":"2025-06-03T14:34:57","date_gmt":"2025-06-03T12:34:57","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/?p=1581"},"modified":"2025-06-03T14:34:57","modified_gmt":"2025-06-03T12:34:57","slug":"pega-studie-zeigt-technische-schulden-gefaehrden-die-einfuehrung-von-ki","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2025\/06\/03\/pega-studie-zeigt-technische-schulden-gefaehrden-die-einfuehrung-von-ki\/","title":{"rendered":"Pega-Studie zeigt: Technische Schulden gef\u00e4hrden die Einf\u00fchrung von KI"},"content":{"rendered":"<p>Auf der PegaWorld in Las Vegas stellte Pegasystems eine gemeinsam mit dem Forschungsunternehmen Savanta durchgef\u00fchrte Studie vor. Aus ihr geht hervor, dass technische Schulden und eine nach wie vor starke Abh\u00e4ngigkeit von veralteten Legacy-Systemen und -Anwendungen Unternehmen bei der Einf\u00fchrung K\u00fcnstlicher Intelligenz behindern. F\u00fcr die Studie wurden mehr als 500 IT-Entscheidungstr\u00e4ger in Unternehmen weltweit zu den Herausforderungen durch technische Schulden und den Fortschritten bei der Modernisierung veralteter Techniken befragt.<\/p>\n<p>Laut der Studie sind mehr als zwei Drittel der Befragten (68 %) der Meinung, dass veraltete Systeme und Anwendungen ihr Unternehmen daran hindern, moderne Techniken vollumf\u00e4nglich zu nutzen. Eine \u00fcberw\u00e4ltigende Mehrheit (88 %) ist zudem besorgt dar\u00fcber, dass sich die technischen Schulden negativ auf ihre F\u00e4higkeit auswirken, mit agileren, innovativeren Wettbewerbern Schritt zu halten. Jeder Dritte (29 %) gab bei dieser Frage sogar an, \u201eklare\u201c oder \u201eerhebliche\u201c Bedenken zu haben. Mehr als die H\u00e4lfte (57 %) r\u00e4umt ein, dass ihre Abh\u00e4ngigkeit von Legacy-Systemen \u201ewahrscheinlich\u201d oder \u201esehr wahrscheinlich\u201c dazu f\u00fchrt, dass Kunden aufgrund der daraus resultierenden schlechten Erfahrungen abwandern.<\/p>\n<p>Zu den weiteren Ergebnisse der Studie z\u00e4hlen unter anderem:<\/p>\n<ul>\n<li>Abh\u00e4ngigkeit von Legacy-Systemen: Fast die H\u00e4lfte (48 %) der Befragten erkl\u00e4rt, dass die Legacy-Systeme nach wie vor gesch\u00e4ftskritisch sind und sie deshalb nicht darauf verzichten k\u00f6nnen \u2013 obwohl sie dies gerne w\u00fcrden. Fast die H\u00e4lfte (47 %) gibt an, dass ihre \u00e4lteste Legacy-Anwendung zwischen 11 und 20 Jahre alt ist, w\u00e4hrend mehr als jeder Zehnte (16 %) Anwendungen betreibt, die zwischen 21 und 30 Jahre alt sind.<\/li>\n<li>Ineffizienz von Legacy-Systemen: Zwei Drittel (68 %) der Befragten geben an, dass Legacy-Systeme ihr Unternehmen daran hindern, so effektiv wie m\u00f6glich zu arbeiten. Als Hauptgr\u00fcnde nennen sie den Zeitaufwand f\u00fcr die Wartung (44 %), die Wartungskosten sowie die Isolierung durch nicht miteinander verbundene Systeme (jeweils 37 %). Lediglich 7 % sind der Meinung, dass Legacy-Anwendungen keinerlei Probleme f\u00fcr ihr Unternehmen verursachen.<\/li>\n<li>Konsequenzen f\u00fcr die Kundenzentrierung: Drei Viertel (74 %) der Befragten stimmen zu, dass ihr Unternehmen Investitionen zur Steigerung der Rentabilit\u00e4t Vorrang vor Ma\u00dfnahmen zur Verbesserung des Kundenerlebnisses einr\u00e4umt, beispielsweise Technologien zur Modernisierung veralteter Anwendungen. Dies deckt sich mit einer von Pega Anfang dieses Jahres durchgef\u00fchrten Verbraucherumfrage. Dabei waren 69 % der Befragten der Meinung, dass Unternehmen bei ihren IT-Investitionen den Gewinn \u00fcber ein positives Kundenerlebnis stellen. Dies k\u00f6nnte auch erkl\u00e4ren, warum jeder Dritte (32 %) angibt, dass die durchschnittliche Bearbeitungszeit f\u00fcr Kundenanfragen in den letzten 12 Monaten um 26 bis 50 % gestiegen ist \u2013 eine direkte Folge davon, dass die Mitarbeiter veraltete Legacy-Anwendungen nutzen.<\/li>\n<\/ul>\n<p>Unsere aktuelle Studie zeigt, wie leicht Unternehmen durch veraltete, schwer zu bedienende und ressourcenintensive Systeme ausgebremst werden k\u00f6nnen \u2013 und damit eine Kultur der Verschwendung in der Organisation zementieren\u201c, erkl\u00e4rt Don Schuerman, Chief Technology Officer bei Pegasystems. \u201eDie direkten Kosten f\u00fcr Unternehmen sind zwar erheblich, doch die wahren Kosten der technischen Schulden betreffen das Erlebnis, das Kunden heute erwarten und verdienen. Es ist f\u00fcr Unternehmen an der Zeit, ihre Denkweise zu \u00e4ndern, die Leistungsf\u00e4higkeit generativer KI durch Innovationen wie Pega Blueprint zu nutzen, eine schnelle und effiziente Transformation ihrer Altsysteme voranzutreiben und sich aus dem Teufelskreis der technischen Altlasten zu befreien \u2013 bevor sie ihre Kunden endg\u00fcltig verlieren.&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auf der PegaWorld in Las Vegas stellte Pegasystems eine gemeinsam mit dem Forschungsunternehmen Savanta durchgef\u00fchrte Studie vor. Aus ihr geht hervor, dass technische Schulden und eine nach wie vor starke Abh\u00e4ngigkeit von veralteten Legacy-Systemen und -Anwendungen Unternehmen bei der Einf\u00fchrung K\u00fcnstlicher Intelligenz behindern. F\u00fcr die Studie wurden mehr als 500 IT-Entscheidungstr\u00e4ger in Unternehmen weltweit zu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,12],"tags":[],"class_list":["post-1581","post","type-post","status-publish","format-standard","hentry","category-firmen-news","category-pc-software"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=1581"}],"version-history":[{"count":1,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1581\/revisions"}],"predecessor-version":[{"id":1582,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1581\/revisions\/1582"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=1581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=1581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=1581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}