{"id":1717,"date":"2025-08-29T13:38:45","date_gmt":"2025-08-29T11:38:45","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/?p=1717"},"modified":"2025-08-29T13:39:18","modified_gmt":"2025-08-29T11:39:18","slug":"deutsche-glasfaser-e-trencher-ermoeglicht-energiesparenden-glasfaser-ausbau","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2025\/08\/29\/deutsche-glasfaser-e-trencher-ermoeglicht-energiesparenden-glasfaser-ausbau\/","title":{"rendered":"Deutsche Glasfaser: E-Trencher erm\u00f6glicht energiesparenden Glasfaser-Ausbau"},"content":{"rendered":"<p>Deutsche Glasfaser baut im Landkreis Neuwied ein modernes und hochleistungsf\u00e4higes Glasfasernetz. Mit dem neuen Netzkonzept 4.0 setzt das Unternehmen in diesem Landkreis auf einen besonders energieeffizienten und ressourcenschonenden Ausbau und Netzbetrieb. Bei den Tiefbauarbeiten vor Ort kommt nun erstmals auch ein E-Trencher zum Einsatz. \u201eAls unser Baupartner Artemis von der neuen E-Fr\u00e4se berichtete, war schnell klar: Die wollen wir auf jeden Fall einsetzen!\u201c, berichtet Blerta Ramadani, Partnermanagerin bei Deutsche Glasfaser. \u201eDie Vorteile der Maschine haben uns auch deshalb \u00fcberzeugt, weil sie unseren nachhaltigen und effizienten Angang vor Ort perfekt unterst\u00fctzt.\u201c<\/p>\n<figure id=\"attachment_1719\" aria-describedby=\"caption-attachment-1719\" style=\"width: 308px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1719\" src=\"https:\/\/www.lan-wan-telecom.de\/wp-content\/uploads\/2025\/08\/etrench-s.jpg\" alt=\"\" width=\"308\" height=\"173\" srcset=\"https:\/\/www.lan-wan-telecom.de\/wp-content\/uploads\/2025\/08\/etrench-s.jpg 500w, https:\/\/www.lan-wan-telecom.de\/wp-content\/uploads\/2025\/08\/etrench-s-300x169.jpg 300w\" sizes=\"auto, (max-width: 308px) 100vw, 308px\" \/><figcaption id=\"caption-attachment-1719\" class=\"wp-caption-text\">Der E-Trencher im Deutsche Glasfaser Projekt in Leubsdorf im Einsatz<\/figcaption><\/figure>\n<p>Die konventionelle Fr\u00e4se ist bereits in zahlreichen Projekten von Deutsche Glasfaser im Einsatz und geh\u00f6rt zu den pr\u00e4ferierten Verfahren\u2013 auch im Landkreis Neuwied. Sie wird von Baupartnern des Unternehmens bei Arbeiten auf asphaltierten Fl\u00e4chen eingesetzt. Die Asphaltdecke wird gefr\u00e4st, so dass ein schmaler Graben entsteht, in dem dann die Leerrohre auf einer Tiefe von 40 Zentimetern verlegt werden. Durch diese Vorgehensweise k\u00f6nnen Baufelder so effizient bearbeitet werden, dass der Stra\u00dfenabschnitt bis zum Abschluss des Arbeitstages provisorisch wieder hergestellt werden kann. So bleibt keine offene Baugrube, der Abschnitt kann direkt wieder befahren bzw. begangen werden. Dies ist einer der Gr\u00fcnde, warum der Einsatz der Fr\u00e4se f\u00fcr Deutsche Glasfaser zu den pr\u00e4ferierten Verfahren beim Leitungsbau z\u00e4hlt. Weitere Gr\u00fcnde: Das Verfahren kann den Bauprozess um bis zu 70 Prozent beschleunigen und ist genauso zuverl\u00e4ssig wie andere konventionelle Methoden.<\/p>\n<p>\u201eKonventionelle Fr\u00e4sen haben wir bereits l\u00e4nger im Angebot, sie erfreuen sich gro\u00dfer Beliebtheit beim Glasfaserausbau\u201c, sagt Christos Touloupis, Sales Manager von Domka Maschinenbau. \u201eDen E-Trencher haben wir ganz neu entwickelt. In diesem Projekt von Deutsche Glafaser setzen wir ihn nun zum ersten Mal ein.\u201c Bei herk\u00f6mmlichen, dieselbetriebenen Fr\u00e4sen erh\u00f6ht sich der L\u00e4rmpegel w\u00e4hrend der Bauarbeiten deutlich. Mit dem Akku-betriebenen Modell k\u00f6nnen wir die Bauarbeiten bei gleicher Bauleistung deutlich leiser und ohne die Emissionen eines Dieselmotors durchgef\u00fchrt werden \u2013 eine erhebliche Entlastung f\u00fcr die Arbeiter und Anwohner.<\/p>\n<p>Artemis, Baupartner von Deutsche Glasfaser, hat das erste Modell des E-Trenchers der Firma Domka mit Sitz in K\u00f6ln, erworben. Der Einsatz im Landkreis Neuwied ist somit eine Premiere. \u201e\u00dcberzeugt haben uns am Ende des Tages die Leistungsdaten\u201c, berichtet Stefan Tebbe, Gesch\u00e4ftsf\u00fchrer von Artemis. \u201eDie Fr\u00e4se hat eine durchschnittliche Leistungsf\u00e4higkeit von drei bis vier Stunden pro Batterieladung. Dies entspricht der Strecke, die wir an einem Tag bearbeiten k\u00f6nnen.\u201c Der E-Trencher bietet weitere Vorteile: Die Maschine kann an jeder handels\u00fcblichen Lades\u00e4ule f\u00fcr E-Autos aufgeladen werden und unterscheidet sich lediglich im Antrieb von seinen dieselbetriebenen \u201eKollegen\u201c. Die Einarbeitungszeit f\u00fcr die Bediener wird damit auf ein Minimum reduziert.<\/p>\n<p>Im rheinland-pf\u00e4lzischen Landkreis Neuwied ist der Einsatz des E-Trenchers nicht das erste Pilotprojekt, das Deutsche Glasfaser umsetzt. In Vettelscho\u00df hatte das Unternehmen den Glasfaserausbau 2024 bereits erstmals nach einem neuen Netzkonzept durchgef\u00fchrt. Auf diese Weise erfolgt nun auch der Ausbau in Leubsdorf, abermals gemeinsam mit dem Baupartner Artemis. Das Netzkonzept 4.0 erm\u00f6glicht es, den Ausbau und Betrieb des Glasfasernetzes noch energie- und ressourcenschonender zu gestalten. Es verbindet modernste Hardware-Komponenten und zukunftsweisende Prozesstechnik. Die neue Ausbauvariante reduziert den Strombedarf auf rund 20 % eines bisherigen Kupfernetzes.<\/p>\n<p>Sollten die Erfahrungen beim Einsatz des E-Trenchers den Erwartungen entsprechen, wird Deutsche Glasfaser gemeinsam mit Artemis den Einsatz von elektrisch angetriebenen Baumaschinen weiter voranbringen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deutsche Glasfaser baut im Landkreis Neuwied ein modernes und hochleistungsf\u00e4higes Glasfasernetz. Mit dem neuen Netzkonzept 4.0 setzt das Unternehmen in diesem Landkreis auf einen besonders energieeffizienten und ressourcenschonenden Ausbau und Netzbetrieb. Bei den Tiefbauarbeiten vor Ort kommt nun erstmals auch ein E-Trencher zum Einsatz. \u201eAls unser Baupartner Artemis von der neuen E-Fr\u00e4se berichtete, war schnell [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,5],"tags":[],"class_list":["post-1717","post","type-post","status-publish","format-standard","hentry","category-firmen-news","category-networks"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=1717"}],"version-history":[{"count":2,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1717\/revisions"}],"predecessor-version":[{"id":1721,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/1717\/revisions\/1721"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=1717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=1717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=1717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}