{"id":205,"date":"2021-09-20T10:25:11","date_gmt":"2021-09-20T08:25:11","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/index.php\/2021\/09\/20\/managed-postgresql-als-public-preview\/"},"modified":"2021-09-20T10:25:11","modified_gmt":"2021-09-20T08:25:11","slug":"managed-postgresql-als-public-preview","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2021\/09\/20\/managed-postgresql-als-public-preview\/","title":{"rendered":"Managed PostgreSQL als Public Preview"},"content":{"rendered":"<p>Instaclustr, Managed-Services-Anbieter f\u00fcr Open-Source-Techniken, hat PostgreSQL in das Portfolio seiner Managed-Services-Plattform aufgenommen. Der Service ist als Public Preview ab sofort verf\u00fcgbar. Managed PostgreSQL bietet f\u00fcr Nutzer der Plattform von Instaclustr eine komplette Datenbankverwaltung und -optimierung sowie umfassenden Support und Monitoring. Bei der Verwendung k\u00f6nnen Nutzer zus\u00e4tzlich auf die Unterst\u00fctzung durch das PostgreSQL-Expertenteam von Instaclustr zur\u00fcckgreifen. Flexibilit\u00e4t garantiert Instaclustr auch beim Hosting f\u00fcr den Service: Er steht f\u00fcr Amazon Web Services, Microsoft Azure und die Google Cloud Platform oder On-Premises zur Verf\u00fcgung. Die Datenbankkomponente erweitert die Plattform, \u00fcber die bereits Cassandra, Elasticsearch, Kafka, Redis und andere Open-Source-Technologien als vollst\u00e4ndige und von Experten verwaltete Services bereitstehen.<\/p>\n<p>Vor allem in der Open-Source-Version erfreut sich PostgreSQL einer zunehmenden Beliebtheit als besonders vielseitige Datenbank, die leicht zu verwenden ist. Die Verwaltung von PostgreSQL im gr\u00f6\u00dferen Ma\u00dfstab ist allerdings deutlich komplexer und bedarf mehr Aufmerksamkeit und Expertise, um Deployments kontinuierlich auf Leistung, Sicherheit und Kosteneffizienz abzustimmen. Praktische Erfahrung ist auch erforderlich, um Unternehmensanforderungen in Bezug auf das fachgerechte Monitoring der Datenbank sowie die Verwaltung von Replicas, Failover, Backup und Version-Upgrades in gesch\u00e4ftskritischen Umgebungen zu erf\u00fcllen.\u00a0Managed PostgreSQL bietet einen schnellen und sicheren Pfad zu einer vollst\u00e4ndig verwalteten und optimierten PostgreSQL-Implementierung. Der Service eignet sich vor allem f\u00fcr Unternehmen, die zwar die Vorteile von PostgreSQL kennen und nutzen wollen, aber vor dem operativen Aufwand zur\u00fcckschrecken, den die Selbstverwaltung mit sich bringt. Das Angebot von Managed PostgreSQL durch Instaclustr ist die konsequente Folge der \u00dcbernahme von credativ. Das globale Beratungsunternehmen mit Hauptsitz in Deutschland hat mehr als 20 Jahre Erfahrung in der Bereitstellung von umfassendem Service und technischem Support f\u00fcr PostgreSQL und andere Open-Source-Datentechniken. Nach nur sechs Monaten seit der Akquisition hat Instaclustr seine Kapazit\u00e4ten \u00fcber die reine Beratung in Sachen PostgreSQL hinaus erweitert und die Datenbank in seine vollst\u00e4ndig verwaltete und Open-Source-Datenmanagement-Plattform aufgenommen.<\/p>\n<p>Um sicherzustellen, dass die Nutzer den gr\u00f6\u00dftm\u00f6glichen Nutzen aus ihren PostgreSQL-Deployments ziehen k\u00f6nnen, stellt Instaclustr auch Support f\u00fcr die Datenbankadministration (DBA) von Anwendungen als optionale Dienstleistung bereit. Der Application DBA Support bezieht sich auf administrative Unterst\u00fctzung, Wartung und Optimierung f\u00fcr die jeweiligen Anwendungskomponenten von Unternehmen, die auf PostgreSQL laufen. \u201eDie leistungsstarke Open-Source-Datenbank PostgreSQL ben\u00f6tigt bei der Verwaltung Expertenwissen, um ihr volles Potenzial zu entfalten. Sie ist daher eine nat\u00fcrliche Erg\u00e4nzung unserer Managed Platform mit reinen Open-Source-Techniken\u201c, berichtet Ben Slater, Chief Product Officer bei Instaclustr. \u201eMit der Public Preview haben Nutzer unserer Plattform die Gelegenheit, durch uns verwaltetes PostgreSQL einzusetzen, egal ob sie auf die Datenbank migrieren oder die Komplexit\u00e4t, sie selbst zu verwalten, reduzieren m\u00f6chten.\u201c\u00a0Nach der Public-Preview-Phase wird die allgemein verf\u00fcgbare Version von Managed PostgreSQL den Support und die Service Level Agreements von Instaclustr beinhalten. Bereits aktive Nutzer k\u00f6nnen mit dem Einsatz von PostgreSQL beginnen, indem sie sich in der Instaclustr-Konsole anmelden und ein PostgreSQL-Cluster erstellen.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Instaclustr, Managed-Services-Anbieter f\u00fcr Open-Source-Techniken, hat PostgreSQL in das Portfolio seiner Managed-Services-Plattform aufgenommen. Der Service ist als Public Preview ab sofort verf\u00fcgbar. Managed PostgreSQL bietet f\u00fcr Nutzer der Plattform von Instaclustr eine komplette Datenbankverwaltung und -optimierung sowie umfassenden Support und Monitoring. Bei der Verwendung k\u00f6nnen Nutzer zus\u00e4tzlich auf die Unterst\u00fctzung durch das PostgreSQL-Expertenteam von Instaclustr zur\u00fcckgreifen. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-205","post","type-post","status-publish","format-standard","hentry","category-networks"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=205"}],"version-history":[{"count":0,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/205\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}