{"id":325,"date":"2022-02-08T10:40:52","date_gmt":"2022-02-08T09:40:52","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/index.php\/2022\/02\/08\/mehr-speed-fuer-lokale-netze\/"},"modified":"2022-02-08T10:40:52","modified_gmt":"2022-02-08T09:40:52","slug":"mehr-speed-fuer-lokale-netze","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2022\/02\/08\/mehr-speed-fuer-lokale-netze\/","title":{"rendered":"Mehr Speed f\u00fcr lokale Netze"},"content":{"rendered":"<p>Durch den starken Anstieg von Cloud-Computing, Streaming, Videokommunikation sowie auch wegen des schnelleren WLAN-6-Standards sto\u00dfen in vielen Unternehmen die lokalen Netze an ihre Grenzen. Wer in seinem Netz schnellere \u00dcbertragungsraten als 1 GBit\/s erreichen m\u00f6chte, dem bietet der US-amerikanische Netzspezialist TRENDnet effiziente und kosteng\u00fcnstige L\u00f6sungen wie beispielsweise die beiden unmanaged 10G Switches TEG-S750 und TEG-S762 l\u00e4sst sich die Bandbreite des Netzes von kleinen und mittleren Unternehmen (KMU) auf 10Gbps erweitern.<\/p>\n<p><!--more--><\/p>\n<p>Der 5-Port 10G Switch TEG-S750 verf\u00fcgt \u00fcber f\u00fcnf dedizierte 10G-Ports mit einer Schaltkapazit\u00e4t von 100 Gbps. Er unterst\u00fctzt auch 2,5G- und 5G-Verbindungen \u00fcber Cat5e-Kabel (oder besser); 10G-Geschwindigkeiten werden \u00fcber Cat6A-Kabel (oder besser) unterst\u00fctzt. Der 6-Port 10G Switch, Modell TEG-S762, verf\u00fcgt \u00fcber zwei dedizierte 10G-Ports und vier dedizierte 2,5G-Ports mit einer Schaltkapazit\u00e4t von 60 Gbit\/s.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"images\/2022\/TEG-S750.jpg\" alt=\"\" width=\"324\" height=\"178\" \/><\/p>\n<p>TEG-S750<\/p>\n<p>Die beiden 10G-Switches TEG-S750 und TEG-S762 bieten eine kosteng\u00fcnstige L\u00f6sung, um jedes Netz mit leistungsstarken Multi-Gigabit-Funktionen auszustatten und so Datenengp\u00e4sse zu vermeiden. Das l\u00fcfterlose Design senkt den Energieverbrauch und die Kosten, w\u00e4hrend st\u00f6rende Ger\u00e4usche f\u00fcr einen leisen Betrieb eliminiert werden. Jeder zuverl\u00e4ssige 10G-Switch verf\u00fcgt \u00fcber ein leichtes Metallgeh\u00e4use, das besonders robust ist.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"images\/2022\/TEG-S762.jpg\" alt=\"\" width=\"321\" height=\"173\" \/><\/p>\n<p>TEG-S762<\/p>\n<p>&#8222;Als Multi-Gigabit-L\u00f6sungen vor ein paar Jahren auf den Markt kamen, gab es nur sehr wenige unterst\u00fctzte Ger\u00e4te, und der Markt war noch nicht ganz bereit daf\u00fcr&#8220;, sagt Evan Davis, Senior Manager of Solutions Engineering bei TRENDnet. &#8222;Aber heute gibt es viel mehr Ger\u00e4te, die es nicht nur unterst\u00fctzen, sondern auch gezielt Multi-Gigabit-Bandbreite nutzen, wie NAS-Ger\u00e4te, Computerserver, Router, Modems und Access Points.&#8220;<\/p>\n<p>Der 5-Port 10G-Switch TEG-S750 und der 6-Port 10G-Switch TEG-S762 sind Teil der wachsenden Reihe von Multi-Gigabit-L\u00f6sungen von TRENDnet, die 10G-, 5G- und 2,5G-Konnektivit\u00e4tsprodukte umfassen. Neben PoE+- und Nicht-PoE-Switches umfassen die Multi-Gigabit-L\u00f6sungen von TRENDnet auch USB-C-Adapter, PCIe-Adapter, PoE+-Injektoren und SFP+-Module.<\/p>\n<p>\u00a0<\/p>\n<p>5-Port 10G-Switch, TEG-S750<\/p>\n<p>\u2022 Unverbindliche Preisempfehlung des Herstellers: \u20ac419,99 EUR inkl. MwSt.<\/p>\n<p>\u2022 Weitere Infos und Datenblatt &#8211;&gt; <a href=\"https:\/\/www.trendnet.com\/langge\/products\/10g-switch\/5-port-10g-switch-TEG-S750-v1\" target=\"_blank\" rel=\"noopener noreferrer\">Weblink<\/a><\/p>\n<p>\u00a0<\/p>\n<p>6-Port 10G-Switch, TEG-S762<\/p>\n<p>\u2022 Unverbindliche Preisempfehlung des Herstellers: \u20ac283,99 EUR inkl. MwSt.<\/p>\n<p>\u2022 Weitere Infos und Datenblatt: &#8211;&gt; <a href=\"https:\/\/www.trendnet.com\/langge\/products\/multigig-switch\/6-port-10g-switch-TEG-S762-v1\" target=\"_blank\" rel=\"noopener noreferrer\">Weblink<\/a><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durch den starken Anstieg von Cloud-Computing, Streaming, Videokommunikation sowie auch wegen des schnelleren WLAN-6-Standards sto\u00dfen in vielen Unternehmen die lokalen Netze an ihre Grenzen. Wer in seinem Netz schnellere \u00dcbertragungsraten als 1 GBit\/s erreichen m\u00f6chte, dem bietet der US-amerikanische Netzspezialist TRENDnet effiziente und kosteng\u00fcnstige L\u00f6sungen wie beispielsweise die beiden unmanaged 10G Switches TEG-S750 und TEG-S762 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-325","post","type-post","status-publish","format-standard","hentry","category-networks"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=325"}],"version-history":[{"count":0,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/325\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}