{"id":354,"date":"2022-03-11T14:00:24","date_gmt":"2022-03-11T13:00:24","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/index.php\/2022\/03\/11\/dominikanischen-republik-tetra-netz-fuer-die-oeffentliche-sicherheit\/"},"modified":"2022-03-11T14:00:24","modified_gmt":"2022-03-11T13:00:24","slug":"dominikanischen-republik-tetra-netz-fuer-die-oeffentliche-sicherheit","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2022\/03\/11\/dominikanischen-republik-tetra-netz-fuer-die-oeffentliche-sicherheit\/","title":{"rendered":"Dominikanischen Republik: TETRA-Netz f\u00fcr die \u00d6ffentliche Sicherheit"},"content":{"rendered":"<p>Im Auftrag des dominikanischen Innenministeriums wurden die letzten Versorgungsl\u00fccken im l\u00e4ndlichen Raum geschlossen und die landesweite Funkabdeckung erreicht.\u00a0Das komplette TETRA-Netz umfasst nun mehr als 200 Basisstationen und wird von s\u00e4mtlichen Polizei- und Rettungskr\u00e4ften des Landes sowie der 911-Notrufzentrale genutzt. Mit ACCESSNET\u00ae-T IP kommuniziert die \u00d6ffentliche Sicherheit in der Dominikanischen Republik \u00fcber ein sicheres, hochverf\u00fcgbares und robustes Funksystem der neuesten TETRA-Generation. Umfassende Kontroll- und Dispatcher-Funktionen tragen zu schnellen Reaktionszeiten und effizientem Arbeiten bei.<\/p>\n<p>Hytera Mobbilfunk ist seit Beginn 2013 federf\u00fchrend an dem Projekt beteiligt und hat alle Ausbauphasen begleitet. Die ersten Basisstationen wurden in der Hauptstadt Santo Domingo aufgebaut, dann wurde das Netz entlang der Hauptverkehrsader Richtung Norden erweitert (Santiago de los Caballeros und die K\u00fcstenregion \u201eZona Norte\u201c). Sukzessive wurde von dort dann das ganze Land mit der neuen TETRA-Funkversorgung ausgestattet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Auftrag des dominikanischen Innenministeriums wurden die letzten Versorgungsl\u00fccken im l\u00e4ndlichen Raum geschlossen und die landesweite Funkabdeckung erreicht.\u00a0Das komplette TETRA-Netz umfasst nun mehr als 200 Basisstationen und wird von s\u00e4mtlichen Polizei- und Rettungskr\u00e4ften des Landes sowie der 911-Notrufzentrale genutzt. Mit ACCESSNET\u00ae-T IP kommuniziert die \u00d6ffentliche Sicherheit in der Dominikanischen Republik \u00fcber ein sicheres, hochverf\u00fcgbares und [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-354","post","type-post","status-publish","format-standard","hentry","category-networks"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=354"}],"version-history":[{"count":0,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/354\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}