{"id":462,"date":"2022-07-13T16:05:39","date_gmt":"2022-07-13T14:05:39","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/index.php\/2022\/07\/13\/ki-und-das-protokoll-macht-der-roboter\/"},"modified":"2022-07-13T16:05:39","modified_gmt":"2022-07-13T14:05:39","slug":"ki-und-das-protokoll-macht-der-roboter","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2022\/07\/13\/ki-und-das-protokoll-macht-der-roboter\/","title":{"rendered":"KI: Und das Protokoll macht der Roboter"},"content":{"rendered":"<p>Klar: K\u00fcnstliche Intelligenz wird \u00fcber kurz oder lang unseren Arbeitsalltag revolutionieren. Aber was hei\u00dft das konkret? Dell Technologies schaut in die Zukunft und skizziert einen ganz normalen B\u00fcrotag im Jahr 2030.\u00a0Die Arbeitswelt von morgen wird sich durch K\u00fcnstliche Intelligenz (KI) von Grund auf ver\u00e4ndern \u2013 darin sind sich die Fachleute einig. Angst davor, irgendwann \u00fcberfl\u00fcssig zu sein, m\u00fcssen wir jedoch nicht haben, denn KI wird den Menschen nicht ersetzen, sondern vor allem unterst\u00fctzen und entlasten.\u00a0Aber wie wird unser Arbeitsalltag dann k\u00fcnftig konkret aussehen? Dell Technologies wagt eine Prognose und beschreibt, wie ein B\u00fcrotag im Jahr 2030 ablaufen k\u00f6nnte:<\/p>\n<p><!--more--><\/p>\n<p>Der Arbeitstag von Projektmanagerin Sonja K\u00f6nig beginnt um 9 Uhr im Homeoffice. Mit einem Fingerschnippen ruft sie ihren digitalen KI-Assistenten, von ihr liebevoll \u201eMister Moneypenny\u201c genannt. Moneypenny liest Sonja kurz die heutigen Termine und Aufgaben vor.\u00a0Um die Organisation der Termine hat sich bereits ihr Cobot (\u201eCollaborative Robot\u201c) gek\u00fcmmert. Alle n\u00f6tigen Infos dazu hat er aus der Kommunikation zwischen Sonja und ihren Kollegen entnommen. Er hat schon ihre Termine in den Kalender eingetragen, die Zugfahrten zu den Ausw\u00e4rtsterminen gebucht und die Kollegen in den Niederlassungen zu den Meetings eingeladen.<br \/>Moneypenny hat auch bereits vorgearbeitet und f\u00fcr Sonja Dossiers mit den wichtigsten Informationen zusammengestellt. Daf\u00fcr hat er Dokumente aus dem Unternehmensnetzwerk mit einer semantischen Inhaltsanalyse ausgewertet. Sonja kann sich voll und ganz auf ihre Meetings konzentrieren. Um die Protokolle muss sie sich dabei ebenfalls nicht k\u00fcmmern, denn die wird Cobot f\u00fchren.<br \/>Vor dem n\u00e4chsten Termin hat Sonja K\u00f6nig noch ein bisschen Zeit. Die nutzt sie, um an der n\u00e4chsten Marketingkampagne zu feilen. Sie ruft Moneypenny. Der erscheint als holografischer Avatar im Raum und Sonja fragt ihn, ob es jemanden im Unternehmen gibt, der schon einmal \u00e4hnliche Themen bearbeitet hat. Ja, Moneypenny kennt jemanden, denn er scannt das Netzwerk kontinuierlich und wei\u00df deshalb, dass ein Kollege aus Frankreich erst k\u00fcrzlich eine ganz \u00e4hnliche Kampagne erstellt hat.<br \/>Moneypenny vereinbart mit diesem Kollegen gleich ein Online-Meeting und ruft ihn direkt an. In ihrem Gespr\u00e4ch unterhalten sich Sonja und ihr Kollege einfach in ihrer jeweiligen Muttersprache. Der Cobot von Sonja \u00fcbersetzt simultan in beide Richtungen und imitiert dabei die Stimmen der beiden Gespr\u00e4chspartner t\u00e4uschend echt. Das Protokoll liefert Moneypenny nur wenige Sekunden nach dem Ende des Meetings ab.\u00a0Sonja muss zum Ausw\u00e4rtstermin. Moneypenny hat ihr ein Taxi bestellt, dass sie rechtzeitig zum Bahnhof bringt. W\u00e4hrend der Fahrt geht sie schnell noch einmal das Briefing durch und fragt bei Moneypenny nach, wenn ihr noch irgendwelche Infos fehlen.\u00a0<br \/>Ihr Cobot erledigt parallel noch ein paar Kundenanfragen, die per E-Mail oder telefonisch bei Sonja eingetrudelt sind. Au\u00dferdem erinnert er sie daran, dass sie heute Nachmittag noch einen Online-Workshop hat, in dem sie neue Funktionen von Moneypenny kennenlernen wird. Solche Upskilling-Workshops sind ein fester Bestandteil ihres Arbeitsalltags.\u00a0Auch wenn vieles davon noch Zukunftsmusik ist: Diese Zukunft f\u00e4ngt heute an, denn erste KI-Anwendungen wie Datenanalysen, Chatbots oder digitale Assistenten haben bereits damit begonnen, die Unternehmenswelt zu erobern. Laut Ute Riester, Senior Manager Field Product Management bei Dell Technologies Deutschland, tun die Unternehmen deshalb gut daran, ihre Mitarbeiter schon jetzt auf die neue Arbeitswelt vorzubereiten.\u00a0\u201eUnternehmen sollten damit beginnen, ihre Mitarbeiter f\u00fcr die Nutzung von KI zu qualifizieren und sie durch regelm\u00e4\u00dfige Schulungen immer auf dem aktuellen Stand der Technik halten\u201c, erkl\u00e4rt Riester. \u201eDann k\u00f6nnen sie das Potenzial dieser Technologie voll aussch\u00f6pfen. Sie werden von eint\u00f6nigen und anspruchslosen Routinet\u00e4tigkeiten entlastet und gewinnen mehr Freiraum f\u00fcr sinnvolle, kreative und nachhaltige Aufgaben.\u201c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Klar: K\u00fcnstliche Intelligenz wird \u00fcber kurz oder lang unseren Arbeitsalltag revolutionieren. Aber was hei\u00dft das konkret? Dell Technologies schaut in die Zukunft und skizziert einen ganz normalen B\u00fcrotag im Jahr 2030.\u00a0Die Arbeitswelt von morgen wird sich durch K\u00fcnstliche Intelligenz (KI) von Grund auf ver\u00e4ndern \u2013 darin sind sich die Fachleute einig. Angst davor, irgendwann \u00fcberfl\u00fcssig [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-462","post","type-post","status-publish","format-standard","hentry","category-networks"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=462"}],"version-history":[{"count":0,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/462\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}