{"id":509,"date":"2022-09-15T15:38:42","date_gmt":"2022-09-15T13:38:42","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/index.php\/2022\/09\/15\/strato-sagt-hej-sverige\/"},"modified":"2022-09-15T15:38:42","modified_gmt":"2022-09-15T13:38:42","slug":"strato-sagt-hej-sverige","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2022\/09\/15\/strato-sagt-hej-sverige\/","title":{"rendered":"STRATO sagt \u201eHej, Sverige\u201c"},"content":{"rendered":"<p>Der Webhoster STRATO steigt in den schwedischen Hostingmarkt ein. Mit diesem Schritt setzt das Unternehmen seinen Erfolgskurs innerhalb Europas fort. Zum Start umfasst das Angebot neben dem klassischen Hosting unter anderem den beliebten Homepage-Baukasten, den Cloud-Speicher HiDrive sowie den Webshop.\u200b<\/p>\n<p><!--more--><\/p>\n<p>Schweden ist digital besonders fortgeschritten \u2013 gerade die junge Generation ist dort sehr internetaffin und macht dem Begriff \u201eDigital Native\u201c alle Ehre. F\u00fcr STRATO bietet der schwedische Markt damit optimale Voraussetzungen f\u00fcr den n\u00e4chsten internationalen Schritt. Nachdem der Webhoster aus Berlin bereits in Spanien, Frankreich, Gro\u00dfbritannien und den Niederlanden aktiv ist, launcht er sein Angebot nun auch f\u00fcr Schweden.<\/p>\n<p>\u201eDie schwedischen Nutzerinnen und Nutzer werden nicht nur von unserer 25-j\u00e4hrigen Erfahrung im Hosting-Bereich profitieren\u201c, betont Claudia Frese, CEO von STRATO. \u201eWir wissen, dass Datensicherheit und Klimaschutz in Schweden eine gro\u00dfe Rolle spielen. Den Sicherheitsbed\u00fcrfnissen kommen wir unter anderem mit unseren T\u00dcV-zertifizierten Rechenzentren in Deutschland nach. Als erster gesamt-klimaneutraler Anbieter in diesem Markt zeigen wir zudem, dass STRATO auch den Umweltschutz gro\u00dfschreibt.\u201c\u00a0<\/p>\n<p>Zum Start bietet STRATO k\u00fcnftigen Kundinnen und Kunden unter www.strato.se bereits einen Gro\u00dfteil seines Produktportfolios, darunter klassisches und WordPress-Hosting sowie mehr als 120 Domainendungen. Neu dazu z\u00e4hlen die Top-Level-Domains \u201e.se\u201c sowie \u201e.nu\u201c \u2013 was im Schwedischen \u201ejetzt\u201c bedeutet. Beim Bef\u00fcllen der Domains mit Inhalten helfen der Homepage-Baukasten von STRATO sowie die L\u00f6sung Webshop Now \u2013 mit ihnen realisieren zuk\u00fcnftig auch die Nutzerinnen und Nutzer in Schweden ihre Ideen f\u00fcr Webseiten oder starten ihren eigenen Online-Shop. F\u00fcr die notwendige Datensicherheit bietet STRATO SSL-Zertifikate f\u00fcr Webseiten an, durch deren Einsatz Website-Betreibende ihrer DSGVO-Pflicht nachkommen. Die Secure-Sockets-Layer-Verschl\u00fcsselung kennzeichnet Websites als sicher und sch\u00fctzt sensible Informationen vor Missbrauch. Zum Speichern und Teilen von Fotos, Videos oder anderen Medien stehen der Cloud-Speicher HiDrive und der Dienst HiDrive Share zur Verf\u00fcgung. \u00dcberdies ist mit STRATO Mail auch ein professioneller E-Mail-Dienst f\u00fcr Privatpersonen und Unternehmen Teil des Startangebots.\u00a0<\/p>\n<p>Zum Marktstart sind nicht nur die Produktseiten und s\u00e4mtliche Kunden- und Produkt-Log-ins auf Schwedisch verf\u00fcgbar. Auch der Kundenservice, den STRATO kostenfrei f\u00fcr alle Produkte anbietet, ist von Beginn an in der Landessprache erreichbar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Webhoster STRATO steigt in den schwedischen Hostingmarkt ein. Mit diesem Schritt setzt das Unternehmen seinen Erfolgskurs innerhalb Europas fort. Zum Start umfasst das Angebot neben dem klassischen Hosting unter anderem den beliebten Homepage-Baukasten, den Cloud-Speicher HiDrive sowie den Webshop.\u200b<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-509","post","type-post","status-publish","format-standard","hentry","category-networks"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=509"}],"version-history":[{"count":0,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/509\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}