{"id":567,"date":"2023-01-26T14:54:00","date_gmt":"2023-01-26T13:54:00","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/index.php\/2023\/01\/26\/vde-fnn-vereinfacht-einzelnachweisverfahren-fuer-den-anschluss-von-wasserkraftwerken\/"},"modified":"2023-01-26T14:54:00","modified_gmt":"2023-01-26T13:54:00","slug":"vde-fnn-vereinfacht-einzelnachweisverfahren-fuer-den-anschluss-von-wasserkraftwerken","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2023\/01\/26\/vde-fnn-vereinfacht-einzelnachweisverfahren-fuer-den-anschluss-von-wasserkraftwerken\/","title":{"rendered":"VDE FNN vereinfacht Einzelnachweisverfahren f\u00fcr den Anschluss von Wasserkraftwerken"},"content":{"rendered":"<p>Derzeit liegt die Erzeugungsleistung von Wasserkraftwerken bei rund 5.000 Megawatt. Um mehr Wasserkraft ins Netz zu holen, hat VDE FNN mit den \u00fcberarbeiteten Technischen Anschlussregeln (TAR) Mittelspannung (Novelle 2023) das Einzelnachweisverfahren vereinfacht (VDE-AR-N 4110). Damit alle Erzeugungsanlagen zur Systemstabilit\u00e4t beitragen, m\u00fcssen sie die entsprechenden Eigenschaften vor dem Netzanschluss nachweisen. F\u00fcr kleinere Erzeugungsanlagen mit einer Leistung zwischen 135 und 950 Kilowatt, die mit individuell konstruierten Erzeugungseinheiten wie Generator oder Turbine arbeiten \u2013 vor allem Wasserkraftanlagen \u2013 waren dazu bisher umfangreiche Simulationen und Modelle notwendig. Mit dem neuen vereinfachten Verfahren ist dies nicht mehr erforderlich. Dadurch sinken die Kosten f\u00fcr die Zertifizierung. Zus\u00e4tzlich wurde der Nachweisprozess vereinfacht. Bereits bestehende Wasserkraftwerke k\u00f6nnen nach Umbau oder Erneuerung mit einem \u00fcberschaubaren Aufwand weiter einspeisen.<\/p>\n<p>Bis 2025 planen die Experten bei VDE FNN umfangreiche \u00dcberarbeitungen der Technischen Anschlussregeln f\u00fcr s\u00e4mtliche Spannungsebenen. Die Wechselrichter von Erzeugungsanlagen m\u00fcssen zuk\u00fcnftig wichtige Beitr\u00e4ge f\u00fcr die Systemstabilit\u00e4t leisten, da diese bei 100 Prozent Erneuerbaren nicht mehr von den gro\u00dfen konventionellen Kraftwerken zur Verf\u00fcgung gestellt werden. Zudem sollen in der Niederspannung mehrere Netzanschl\u00fcsse in einem Geb\u00e4ude oder Messeinrichtungen f\u00fcr den Betrieb von Energiemanagementsystemen ebenso aufgenommen werden wie Regeln f\u00fcr den Einbau von modernen Messeinrichtungen in Kundenanlagen. Auch die Anforderungen f\u00fcr den Netzanschluss und Betrieb von E-Mobilit\u00e4t (bidirektionales Laden), Notstromaggregaten und Speichern werden aktualisiert. Dabei sollen weitere Vereinfachungen und Verbesserungen des Nachweisprozesses erfolgen. Die Systemeigenschaften von Erzeugungsanlagen und deren Nachweise sind besonders wichtig, damit erneuerbare Anlagen Gro\u00dfkraftwerke abl\u00f6sen k\u00f6nnen.<\/p>\n<h4>Prozess unter Zeitdruck<\/h4>\n<p>Der Aktualisierungsbedarf von Technischen Anschlussregeln wird sp\u00e4testens alle f\u00fcnf Jahre \u00fcberpr\u00fcft. Macht die technologische oder politische Entwicklung einen kurzfristigere Anpassung notwendig, so erarbeitet eine VDE FNN Projektgruppe einen Entwurf und ver\u00f6ffentlicht diesen. Jede Person kann dazu innerhalb von zwei Monaten \u00c4nderungsvorschl\u00e4ge abgeben. Eingegangene \u00c4nderungsvorschl\u00e4ge werden in der Projektgruppe gepr\u00fcft und soweit wie m\u00f6glich ber\u00fccksichtigt. Dies n\u00fctzt der Qualit\u00e4t der Regeln, nimmt aber auch Zeit in Anspruch.\u00a0Die Novelle 2023 der TAR Mittelspannung ist bereits inhaltlich finalisiert und nun als Vorab-Ver\u00f6ffentlichung im VDE Shop verf\u00fcgbar. Diese verschafft Anwendern Vorlauf f\u00fcr die Umsetzung. Die Vorab-Version wird derzeit bei der Europ\u00e4ischen Kommission notifiziert und tritt danach erfahrungsgem\u00e4\u00df unver\u00e4ndert in Kraft \u2013 geplant ist dies f\u00fcr April 2023.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Derzeit liegt die Erzeugungsleistung von Wasserkraftwerken bei rund 5.000 Megawatt. Um mehr Wasserkraft ins Netz zu holen, hat VDE FNN mit den \u00fcberarbeiteten Technischen Anschlussregeln (TAR) Mittelspannung (Novelle 2023) das Einzelnachweisverfahren vereinfacht (VDE-AR-N 4110). Damit alle Erzeugungsanlagen zur Systemstabilit\u00e4t beitragen, m\u00fcssen sie die entsprechenden Eigenschaften vor dem Netzanschluss nachweisen. F\u00fcr kleinere Erzeugungsanlagen mit einer Leistung [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-567","post","type-post","status-publish","format-standard","hentry","category-networks"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=567"}],"version-history":[{"count":0,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/567\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}