{"id":594,"date":"2023-03-17T16:30:24","date_gmt":"2023-03-17T15:30:24","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/index.php\/2023\/03\/17\/wie-live-streaming-multimedialer-inhalte-in-echtzeit-industrielle-prozesse-veraendern-wird\/"},"modified":"2023-03-17T16:30:24","modified_gmt":"2023-03-17T15:30:24","slug":"wie-live-streaming-multimedialer-inhalte-in-echtzeit-industrielle-prozesse-veraendern-wird","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2023\/03\/17\/wie-live-streaming-multimedialer-inhalte-in-echtzeit-industrielle-prozesse-veraendern-wird\/","title":{"rendered":"Wie Live-Streaming multimedialer Inhalte in Echtzeit industrielle Prozesse ver\u00e4ndern wird"},"content":{"rendered":"<p>Video\u00fcbertragung ist in Industrie und Logistik bereits weit verbreitet. Allerdings beschr\u00e4nkten sich die Anwendungen bisher weitgehend auf \u00dcberwachungs- und Sicherheitsfunktionen. Ist eine unmittelbare Reaktion erforderlich, konnte man bisher per Video jedoch nicht schnell und pr\u00e4zise genug reagieren. Das \u00e4ndert sich nun: Netze mit extrem niedrigen Latenzzeiten und hoher Bandbreite machen solche Einsatzszenarien nun m\u00f6glich.<\/p>\n<p><!--more--><\/p>\n<p>\u00a0Echtzeit-Multimedia-L\u00f6sungen mit Extended-Reality-Funktionen, wie etwa Real-time eXtended Reality Multimedia (RXRM) von Nokia, integrieren 360\u00b0-Video und r\u00e4umliches 3D-Audio. Sie erm\u00f6glichen aus der Ferne ein besseres Verst\u00e4ndnis komplexer Situationen in Industriebetrieben und erh\u00f6hen die Produktivit\u00e4t und Mitarbeiter-Sicherheit. Mitarbeitende m\u00fcssen nicht mehr um die Welt reisen, um an entlegenen Orten wie Offshore-Anlagen bestimmte T\u00e4tigkeiten durchzuf\u00fchren. Auch Fertigungsprozesse k\u00f6nnen durch Fernsteuerung und -\u00fcberwachung effizienter und sicherer werden. Ein praktisches Beispiel ist das gemeinsame Entwicklungsprojekt von Nokia und dem finnischen Forschungszentrum VTT, in dem das Potenzial von Echtzeit-Multimedia-Streaming f\u00fcr Industrie 4.0 im Bergbau untersucht wird.<\/p>\n<h4>Niedrige Latenz und Bandbreitenoptimierung\u00a0<\/h4>\n<p>Eine bandbreitenoptimierte und \u201eechtzeitf\u00e4hige\u201c Extended-Reality-Multimedia-Technologie ist besonders dann wichtig, wenn die Netzkapazit\u00e4t begrenzt ist und von verschiedenen Anwendungen gemeinsam genutzt wird. Die L\u00f6sung von Nokia beispielsweise reduziert den Bandbreitenbedarf um bis zu 90 Prozent, ohne wahrnehmbare visuelle Qualit\u00e4tseinbu\u00dfen. Das ist ein entscheidender Vorteil, sobald mehrere Mitarbeiter gleichzeitig beteiligt sind. Die L\u00f6sung kann sowohl anwendungsnah am Rand (Edge) des Netzes als auch in der privaten oder \u00f6ffentlichen Cloud eingesetzt werden. Offene Schnittstellen sorgen daf\u00fcr, dass die L\u00f6sung f\u00fcr aktuelle und auch zuk\u00fcnftige industrielle Anwendungsf\u00e4lle genutzt werden kann. Doch in welchen Bereichen ist der wirtschaftliche Nutzen des Echtzeit-Live-Streamings multimedialer Inhalte f\u00fcr die Industrie am gr\u00f6\u00dften? Es sind vor allem vier Bereiche:<\/p>\n<p>Viele Betriebe setzen IoT-Sensoren in ihren Produktionslinien ein. Sie dienen haupts\u00e4chlich der Anlagen\u00fcberwachung und der Bereitstellung von Daten f\u00fcr die Qualit\u00e4tskontrolle \u2013 zwei Bereiche, in denen Echtzeit-Videostreaming und Extended Reality echte betriebliche Verbesserungen bringen k\u00f6nnen. Heutzutage werden Monitoring-Informationen h\u00e4ufig in Form von Listen oder technischen Diagrammen angezeigt. Die Daten sind visuell von der zu \u00fcberwachenden Maschine getrennt. Multimediale Echtzeitl\u00f6sungen \u00e4ndern dies und bringen Sensordaten und Video zusammen. Durch die nun intuitivere Art, mit den Daten zu arbeiten, k\u00f6nnen die Mitarbeiterinnen und Mitarbeiter den Kontext sofort verstehen und reagieren.<\/p>\n<h4>Mitarbeiterschutz und Effizienz durch Fernsteuerung<\/h4>\n<p>Live-Streaming von multimedialen Inhalten in Echtzeit erm\u00f6glicht die Fernsteuerung von Anlagen und Prozessen, vom Bergbau bis zur Lagerlogistik, mit Sicherheits- und Kostenvorteilen. Ein Beispiel: Logistikzentren sind stark frequentierte Orte mit vielen Fahrzeugen. Je mehr Menschen sich dort aufhalten, desto gr\u00f6\u00dfer ist das Unfallrisiko. Durch die Fernsteuerung der Fahrzeuge mit Hilfe von Extended-Reality-Multimedia-Live-Streaming k\u00f6nnen Logistikunternehmen sicherstellen, dass ihre Mitarbeiterinnen und Mitarbeiter nicht gef\u00e4hrdet werden. Die Entlastung des Personals vor Ort tr\u00e4gt auch zur L\u00f6sung eines weiteren Problems bei, mit dem Logistikunternehmen konfrontiert sind: dem Arbeitskr\u00e4ftemangel. Durch die Nutzung von Sensordaten automatisierter Lagerfahrzeuge bei gleichzeitiger Video\u00fcberwachung kann Extended Reality-Multimedia-Live-Streaming mit weniger Personal mehr erreichen.<\/p>\n<p>Multimedia-Live-Streaming mit geringer Latenz kann auch automatisierte L\u00f6sungen unterst\u00fctzen, die Sicherheitsbedrohungen erkennen sollen. Das minimiert das Risiko menschlicher Fehler und hilft dabei, ungew\u00f6hnliche Situationen besser zu verstehen, die Sicherheit des Personal sicherzustellen und Betriebsanlagen zu sch\u00fctzen. Wird die Technologie beispielsweise in Bahnh\u00f6fen eingesetzt, kann sie Bedrohungen erkennen und proaktiv darauf reagieren. Hochaufl\u00f6sende 360\u00b0-Videobilder bieten nicht nur einen umfassenderen und genaueren \u00dcberblick \u00fcber einen bestimmten Ort, sondern senken auch die Betriebskosten, da eine einzige 360\u00b0-Kamera bis zu acht herk\u00f6mmliche Videokameras ersetzen kann. \u00c4hnliche Vorteile ergeben sich f\u00fcr Logistik- und Produktionsunternehmen mit ihren autonomen Fahrzeugen und Robotern. Generell gilt: Durch Vernetzung und Digitalisierung werden IIoT-Anwendungen, die vor kurzem noch undenkbar schienen, immer allt\u00e4glicher. Mit der Zahl der IIoT-Ger\u00e4te steigt auch die Bedeutung von Cybersicherheit und Datenschutz. Beides zu gew\u00e4hrleisten muss im Mittelpunkt aller technologischen Entwicklungen in diesem Bereich stehen.<\/p>\n<h4>Experten-Support aus der Ferne<\/h4>\n<p>Die Reparatur von Maschinen erfordert oft den Einsatz von Fachleuten mit speziellen Kenntnissen. Es ist jedoch nicht immer m\u00f6glich, die richtige Person vor Ort zu haben. Live-Streaming von multimedialen Inhalten in Echtzeit mit einer Latenzzeit von nahezu Null sorgt daf\u00fcr, dass Support-Anfragen oder Schulungen ohne Zeitverz\u00f6gerung aus der Ferne durchgef\u00fchrt werden k\u00f6nnen. Techniker k\u00f6nnen mit ihren Partnern vor Ort visuell kommunizieren und die Arbeit gemeinsam erledigen. Dazu geh\u00f6ren entsprechende Virtual-Reality-Headsets, die k\u00fcnftig auch mit 3D-Raumklang ausgestattet sein werden und den Mitarbeitenden eine bisher nicht gekannte Immersion erm\u00f6glichen. Indem die Schallrichtung erkannt wird, k\u00f6nnen Probleme schneller gel\u00f6st werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Video\u00fcbertragung ist in Industrie und Logistik bereits weit verbreitet. Allerdings beschr\u00e4nkten sich die Anwendungen bisher weitgehend auf \u00dcberwachungs- und Sicherheitsfunktionen. Ist eine unmittelbare Reaktion erforderlich, konnte man bisher per Video jedoch nicht schnell und pr\u00e4zise genug reagieren. Das \u00e4ndert sich nun: Netze mit extrem niedrigen Latenzzeiten und hoher Bandbreite machen solche Einsatzszenarien nun m\u00f6glich.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-594","post","type-post","status-publish","format-standard","hentry","category-networks"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=594"}],"version-history":[{"count":0,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/594\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}