{"id":640,"date":"2023-06-27T15:58:45","date_gmt":"2023-06-27T13:58:45","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/index.php\/2023\/06\/27\/de-cix-und-swissix-modernisieren-gemeinsam-den-schweizer-internetknoten\/"},"modified":"2023-06-27T15:58:45","modified_gmt":"2023-06-27T13:58:45","slug":"de-cix-und-swissix-modernisieren-gemeinsam-den-schweizer-internetknoten","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2023\/06\/27\/de-cix-und-swissix-modernisieren-gemeinsam-den-schweizer-internetknoten\/","title":{"rendered":"DE-CIX und SwissIX modernisieren gemeinsam den Schweizer Internetknoten"},"content":{"rendered":"<p>DE-CIX, Betreiber von Internetknoten und SwissIX, der Betreiber des gr\u00f6\u00dften Internet Exchanges (IX) in der Schweiz, haben gemeinsam den Schweizer Internetknoten technisch erneuert. Daf\u00fcr wurden die am SwissIX insgesamt 220 angeschlossenen Netze auf die preisgekr\u00f6nte DE-CIX Apollon Plattform migriert. SwissIX zeichnet sich als Verein durch ein nicht gewinnorientiertes und neutrales Peering-Netzwerk aus, das auf insgesamt sieben verschiedene Rechenzentren in der Schweiz verteilt ist. Die Migration fand im laufenden Betrieb in n\u00e4chtlichen Wartungsfenstern statt, um die Auswirkungen auf die Kunden so gering wie m\u00f6glich zu halten.<\/p>\n<p><!--more--><\/p>\n<p>Auch nach der Migration ist DE-CIX f\u00fcr den technischen Betrieb, wie zum Beispiel die Wartung, Instandhaltung und die Weiterentwicklung der SwissIX Interconnection Plattform, verantwortlich. Dies beinhaltet auch die technische Kundenbetreuung und Provisionierung, wohingegen die gesch\u00e4ftliche F\u00fchrung und die Vermarktung des SwissIX weiterhin beim Verein verbleibt.<\/p>\n<p>DE-CIX betreibt in Deutschland insgesamt sechs Internetknoten in verschiedenen Regionen und teilweise in Partnerschaftsmodellen mit lokalen Anbietern. Hierzu geh\u00f6rt der DE-CIX Frankfurt, der mit einem Datendurchsatz von \u00fcber 14 Terabit pro Sekunde einer der gr\u00f6\u00dften Internetknoten Europas ist. Insgesamt ist die DE-CIX Plattform aus \u00fcber 250 deutschen Rechenzentren erreichbar und bietet einfachen Zugang zu modernen Interconnection Services. An rund 50 weltweiten Standorten verbindet DE-CIX Tausende Netzbetreiber (Carrier), Internet Service Provider (ISP), Content-Anbieter (CDN) und Firmennetze aus \u00fcber 100 L\u00e4ndern miteinander und bietet Peering-, Cloud- und Interconnection-Services an. Zusammen bilden die DE-CIX Internetknoten mit einer angeschlossenen Kundenkapazit\u00e4t von rund 130 Terabit das weltweit gr\u00f6\u00dfte neutrale Interconnection-\u00d6kosystem.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DE-CIX, Betreiber von Internetknoten und SwissIX, der Betreiber des gr\u00f6\u00dften Internet Exchanges (IX) in der Schweiz, haben gemeinsam den Schweizer Internetknoten technisch erneuert. Daf\u00fcr wurden die am SwissIX insgesamt 220 angeschlossenen Netze auf die preisgekr\u00f6nte DE-CIX Apollon Plattform migriert. SwissIX zeichnet sich als Verein durch ein nicht gewinnorientiertes und neutrales Peering-Netzwerk aus, das auf insgesamt [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-640","post","type-post","status-publish","format-standard","hentry","category-networks"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=640"}],"version-history":[{"count":0,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/640\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}