{"id":678,"date":"2023-09-21T11:39:31","date_gmt":"2023-09-21T09:39:31","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/index.php\/2023\/09\/21\/anna-dimitrova-wird-cfo-der-deutsche-glasfaser-unternehmensgruppe\/"},"modified":"2023-09-21T11:39:31","modified_gmt":"2023-09-21T09:39:31","slug":"anna-dimitrova-wird-cfo-der-deutsche-glasfaser-unternehmensgruppe","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2023\/09\/21\/anna-dimitrova-wird-cfo-der-deutsche-glasfaser-unternehmensgruppe\/","title":{"rendered":"Anna Dimitrova wird CFO der Deutsche Glasfaser Unternehmensgruppe"},"content":{"rendered":"<p>Anna Dimitrova startet zum 1. Januar 2024 als Chief Financial Officer (CFO) bei Deutsche Glasfaser. In dieser Funktion \u00fcbernimmt sie als Gesch\u00e4ftsf\u00fchrerin die Verantwortung f\u00fcr die Finanzorganisation des Unternehmens. Sie folgt auf Christian van den Boom, der die Leitung der Finanzorganisation derzeit interimistisch aus\u00fcbt.<\/p>\n<p>Anna Dimitrova verf\u00fcgt \u00fcber mehr als zwanzig Jahre Erfahrung in der Telekommunikationsindustrie. Sie ist derzeit Group Financial Controller der Vodafone PLC in London. Zuvor hatte sie mehrere F\u00fchrungspositionen bei Vodafone in Deutschland und in Tschechien inne, unter anderem als CFO, als Gesch\u00e4ftsf\u00fchrerin Finanzen &amp; Strategie und als Chief Transformation Officer.<\/p>\n<p>Bei Deutsche Glasfaser wird Anna Dimitrova die gesamte Finanzorganisation von Accounting, Procurement &amp; Supply Chain \u00fcber Controlling, Planning und Business Intelligence bis zu Value Steering als auch Treasury &amp; Investor Relations verantworten.<\/p>\n<p>\u201eMit Anna Dimitrova haben wir eine hervorragende F\u00fchrungskraft und ausgewiesene Expertin mit tiefer Kenntnis des deutschen Telekommunikationsmarktes als neue Chief Financial Officer gewinnen k\u00f6nnen. Ich freue mich sehr auf die Zusammenarbeit, um gemeinsam unseren dynamischen Wachstumskurs bei Deutsche Glasfaser weiter zu gestalten\u201c, sagt Andreas Pfisterer, CEO der Deutsche Glasfaser Unternehmensgruppe.<\/p>\n<p>\u201eAls f\u00fchrender Digitalversorger schafft Deutsche Glasfaser die Voraussetzung f\u00fcr Digitalisierung und Innovation in unserer Gesellschaft. Die beeindruckende Entwicklung des Unternehmens \u00fcberzeugt mich, dass wir gemeinsam den Weg in eine digital vernetzte Zukunft schneller und effizienter ebnen werden. Ich freue mich, gemeinsam mit den Kolleg:innen von Deutsche Glasfaser auf dieses Ziel hin zu arbeiten\u201c, sagt Anna Dimitrova.<\/p>\n<p>Finance Director Christian van den Boom, der die Leitung der Finanzorganisation derzeit interimistisch aus\u00fcbt, wird zum Jahreswechsel an Anna Dimitrova \u00fcbergeben. \u201eIch m\u00f6chte mich herzlich bei Christian van den Boom bedanken. Christian hat in einer wichtigen Zeit Verantwortung f\u00fcr die Organisation \u00fcbernommen und in den vergangenen Monaten als Interims-CFO eine ausgezeichnete Arbeit geleistet\u201c, so Andreas Pfisterer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anna Dimitrova startet zum 1. Januar 2024 als Chief Financial Officer (CFO) bei Deutsche Glasfaser. In dieser Funktion \u00fcbernimmt sie als Gesch\u00e4ftsf\u00fchrerin die Verantwortung f\u00fcr die Finanzorganisation des Unternehmens. Sie folgt auf Christian van den Boom, der die Leitung der Finanzorganisation derzeit interimistisch aus\u00fcbt. Anna Dimitrova verf\u00fcgt \u00fcber mehr als zwanzig Jahre Erfahrung in der [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-678","post","type-post","status-publish","format-standard","hentry","category-firmen-news"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=678"}],"version-history":[{"count":0,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/678\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}