{"id":828,"date":"2024-01-08T14:02:50","date_gmt":"2024-01-08T13:02:50","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/?p=828"},"modified":"2024-01-08T14:02:50","modified_gmt":"2024-01-08T13:02:50","slug":"bandenwerbung-im-fokus-der-hochschule-kaiserslautern-und-die-sportmarketingagentur-sportfive","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2024\/01\/08\/bandenwerbung-im-fokus-der-hochschule-kaiserslautern-und-die-sportmarketingagentur-sportfive\/","title":{"rendered":"Bandenwerbung im Fokus der Hochschule Kaiserslautern und die Sportmarketingagentur Sportfive"},"content":{"rendered":"<p>Die Hochschule Kaiserslautern und die Sportmarketingagentur Sportfive stellen eine gemeinsame Studie zur Wahrnehmung von Bandenwerbung im Fritz-Walter-Stadion vor.\u00a0In Kooperation zwischen der Hochschule Kaiserslautern und der globalen Sportmarketingagentur Sportfive hat der Digital Media Marketing-Student Tim Schmitt eine spannende wissenschaftliche Studie durchgef\u00fchrt. Er hat die Wahrnehmung von Bandenwerbung im Fritz-Walter-Stadion des 1. FC Kaiserslautern untersucht. Daf\u00fcr nutzte er modernste Technologie in Form der Eye-Tracking Brille Tobii Pro Glasses 3. Die Studie verspricht aufschlussreiche Einblicke in die visuelle Verarbeitung von statischer und digitaler Bandenwerbung.<\/p>\n<p>\u00dcber einen Zeitraum von drei Spieltagen fokussierte sich die Forschung von Tim Schmitt darauf, zum einen die visuelle Wahrnehmung von Zuschauern zu analysieren. Zum anderen sammelte er Erinnerungen der Stadionbesucher an unterschiedliche Formen von Bandenwerbung. Die Tobii Pro Glasses 3 erm\u00f6glichten eine pr\u00e4zise Erfassung der Blickbewegungen, wodurch die Forschung tiefergehende Erkenntnisse \u00fcber die Effektivit\u00e4t und Resonanz der Werbema\u00dfnahmen erlangen konnte.<\/p>\n<p>Die Erkenntnisse versprechen nicht nur eine aufschlussreiche Grundlage f\u00fcr die Vermarktung der Werbefl\u00e4chen im Fritz-Walter-Stadion, sondern dienen auch der verhaltenswissenschaftlichen Forschung an der Hochschule Kaiserslautern.\u00a0Professor Dr. Daniel Stenger, Dozent im Studiengang Digital Media Marketing und wissenschaftlicher Betreuer der Studie, betont die Relevanz der Forschungsergebnisse: \u201eDie visuelle Wahrnehmung von Bandenwerbung im Stadion ist ein Schl\u00fcsselfaktor f\u00fcr den Erfolg dieser Werbema\u00dfnahmen. Unsere Studie bietet nicht nur konkrete Einblicke in das Verhalten der Stadionbesucher, sondern liefert auch wertvolle Erkenntnisse f\u00fcr die Weiterentwicklung von Marketingstrategien im Sportumfeld.\u201c<\/p>\n<p>Die Zusammenarbeit der Hochschule Kaiserslautern und Sportfive unterstreicht die Bedeutung der interdisziplin\u00e4ren Zusammenarbeit zwischen Bildungseinrichtungen und Industrieakteuren. Die Ergebnisse dieser Studie werden nicht nur die Vermarktung im Fritz-Walter-Stadion beeinflussen, sondern bereichern das Verst\u00e4ndnis der Wirksamkeit von Bandenwerbung in der Marketingforschung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Hochschule Kaiserslautern und die Sportmarketingagentur Sportfive stellen eine gemeinsame Studie zur Wahrnehmung von Bandenwerbung im Fritz-Walter-Stadion vor.\u00a0In Kooperation zwischen der Hochschule Kaiserslautern und der globalen Sportmarketingagentur Sportfive hat der Digital Media Marketing-Student Tim Schmitt eine spannende wissenschaftliche Studie durchgef\u00fchrt. Er hat die Wahrnehmung von Bandenwerbung im Fritz-Walter-Stadion des 1. FC Kaiserslautern untersucht. Daf\u00fcr nutzte [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-828","post","type-post","status-publish","format-standard","hentry","category-firmen-news"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=828"}],"version-history":[{"count":1,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/828\/revisions"}],"predecessor-version":[{"id":829,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/828\/revisions\/829"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}