{"id":947,"date":"2024-03-07T15:34:27","date_gmt":"2024-03-07T14:34:27","guid":{"rendered":"https:\/\/www.lan-wan-telecom.de\/?p=947"},"modified":"2024-03-07T15:34:27","modified_gmt":"2024-03-07T14:34:27","slug":"mikro-rechenzentren-im-klinischen-datenbetrieb","status":"publish","type":"post","link":"https:\/\/www.lan-wan-telecom.de\/index.php\/2024\/03\/07\/mikro-rechenzentren-im-klinischen-datenbetrieb\/","title":{"rendered":"Mikro-Rechenzentren im klinischen Datenbetrieb"},"content":{"rendered":"<p>Das Hermann-Josef-Krankenhaus (HJK) Erkelenz, seit 2010 auch akademisches Lehrkrankenhaus der RWTH Aachen, im nordrhein-westf\u00e4lischen Kreis Heinsberg ist ein Krankenhaus in privater Tr\u00e4gerschaft mit 409 Planbetten. Die R\u00e4umlichkeiten sind begrenzt, eine herk\u00f6mmliche L\u00f6sung nicht denkbar. Aufgrund der fortschreitenden Digitalisierung musste aber in eine leistungs- und zukunftsf\u00e4hige IT-Infrastruktur investiert werden. Den Rahmen daf\u00fcr gibt das Krankenhauszukunftsgesetz vor. Ein besonderer Fokus liegt auf der Digitalisierung entlang bundesweiter Standards. Damit wird ein h\u00f6herer Grad der Vernetzung innerhalb des Gesundheitswesens angestrebt.<br \/>\nVierschrank-System IS-1 Edge Row Typ 4 mit zwei in der Reihe angebrachten SideCoolern von SCH\u00c4FER IT-Systems. Das HJK Erkelenz hat, wie viele Krankenh\u00e4user, eine \u00fcber viele Jahrzehnte gewachsene IT-Landschaft. Mittlerweile greifen etwa 600 Client-Rechner auf 100 Server im Haus zu. Die gro\u00dfen Datenmengen werden aktuell von drei Bereichen generiert:<\/p>\n<ul>\n<li>PACS (Picture Archiving and Communication System), ein digitales System zur Verarbeitung, Verwaltung und Archivierung von medizinischen Bildern (CT, R\u00f6ntgen, Ultraschall, MRT)<\/li>\n<li>Labordaten<\/li>\n<li>Patientendaten, wie Berichte und Befunde<\/li>\n<\/ul>\n<p>Datenschutz und Sicherheit ist insbesondere im Gesundheitssektor ein zentrales Thema, welches die IT-Verantwortlichen stetig besch\u00e4ftigt. Gleiches gilt f\u00fcr die Verf\u00fcgbarkeit, also die Ausfallsicherheit, der Systeme. Deshalb werden die Daten im neuen Mikro-Rechenzentrum gespiegelt, um zu jedem Zeitpunkt auf einen redundanten Datensatz zur\u00fcckgreifen zu k\u00f6nnen. Das Grundger\u00fcst der neuen dezentralen Edge-Computing L\u00f6sung bildet das Vierschrank-System IS-1 Edge Row Typ 4 mit zwei in der Reihe angebrachten SideCoolern von SCH\u00c4FER IT-Systems. Die neue Infrastruktur wurde gemeinsam mit dem IT-Dienstleister netgo geplant, gefertigt, vor Ort vollst\u00e4ndig montiert und in Betrieb genommen \u2013 eine schl\u00fcsselfertige L\u00f6sung. Die Nennleistung betr\u00e4gt 30 kW. Kalt- und Warmzonen sind getrennt. Es stehen 139 und 155 nutzbare H\u00f6heneinheiten (HE) zuz\u00fcglich 32 vertikaler Einheiten in den Schottblenden zur Verf\u00fcgung.<\/p>\n<figure id=\"attachment_948\" aria-describedby=\"caption-attachment-948\" style=\"width: 225px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-948\" src=\"https:\/\/www.lan-wan-telecom.de\/wp-content\/uploads\/2024\/03\/HJK_Bild-1_online_c__Schaefer-Werke-GmbH-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.lan-wan-telecom.de\/wp-content\/uploads\/2024\/03\/HJK_Bild-1_online_c__Schaefer-Werke-GmbH-225x300.jpg 225w, https:\/\/www.lan-wan-telecom.de\/wp-content\/uploads\/2024\/03\/HJK_Bild-1_online_c__Schaefer-Werke-GmbH.jpg 768w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><figcaption id=\"caption-attachment-948\" class=\"wp-caption-text\">Vierschrank-System IS-1 Edge Row Typ 4 mit zwei in der Reihe angebrachten SideCoolern von SCH\u00c4FER IT-Systems.<\/figcaption><\/figure>\n<p>Bereits zu Beginn des Projekts hat netgo die Vorteile der SCH\u00c4FER-L\u00f6sung aufgezeigt:\u201enetgo hat es uns erm\u00f6glicht, einen umfassenden \u00dcberblick \u00fcber verschiedene L\u00f6sungen zu erhalten. Besonders beeindruckt hat mich die pers\u00f6nliche Einladung, das Edge-Produktportfolio direkt vor Ort bei SCH\u00c4FER IT-Systems in Betzdorf anzusehen. Dies war eine ganz andere Erfahrung als nur Bilder in Katalogen oder auf Websites zur Verf\u00fcgung zu haben. Die Berater nahmen sich viel Zeit, um uns verschiedene L\u00f6sungsvarianten vorzustellen und Detailfragen zu beantworten\u201c, erkl\u00e4rt J\u00fcrgen Laggner, Leiter Informationstechnologie am HJK Erkelenz.<\/p>\n<p>Zudem organisierte netgo im Vorfeld eine Besichtigung der R\u00e4umlichkeiten im Krankenhaus f\u00fcr die Projektbeteiligten von SCH\u00c4FER, um Details wie Deckenh\u00f6hen, Durchg\u00e4nge und Anschl\u00fcsse kennenzulernen. Laut Laggner wurden \u201ealle Phasen des Projekts vorbildlich von beiden Vertragspartnern abgewickelt\u201c.<\/p>\n<h4>Skalierbare RZ-Infrastruktur von einem erfahrenen L\u00f6sungsanbieter<\/h4>\n<p>Vor allem \u00fcberzeugte den Leiter der Informationstechnologie der \u201ealles aus einer Hand\u201c Ansatz. \u201eDas reduzierte den Planungsaufwand seitens der IT-Abteilung, erh\u00f6hte die Umsetzungsgeschwindigkeit und sparte Kosten ein\u201c, erkl\u00e4rt Laggner weiter. Inkludiert sind s\u00e4mtliche Einheiten wie L\u00f6schanlage, Unterbrechungsfreie Stromversorgung (USV), Stromanschluss, kompakte 19 Zoll Stromverteilung (Powerbox mit 5 HE), K\u00fchlung (Cooling), und Rack-Monitoring. Die \u00dcberwachung beinhaltet wichtige Parameter, darunter Temperatur, Feuchte, Ersch\u00fctterungen, Zutritt (T\u00fcr\u00fcberwachung), St\u00f6rmeldungen von USV, K\u00fchlung sowie die Brandmelde-\/l\u00f6schanlage.<\/p>\n<p>Durch die kompakte L\u00f6sung war man zudem in der Auswahl der R\u00e4umlichkeiten sehr flexibel, weil diese nur einen Raum ben\u00f6tigt. Mit herk\u00f6mmlichen Konzepten w\u00e4re mindestens ein zweiter Raum notwendig gewesen, um beispielsweise die L\u00f6schanlage und Stromversorgung zu installieren.<\/p>\n<ul>\n<li>Edge Computing-Konfigurator von SCH\u00c4FER IT-Systems: <a href=\"https:\/\/www.schaefer-it-systems.de\/de\/edge-computing\/edge-konfigurator\/\" target=\"_blank\" rel=\"noopener\">Edge-Konfigurator<\/a><\/li>\n<li>Informationen zu iQdata von SCH\u00c4FER IT-Systems unter: <a href=\"https:\/\/www.schaefer-it-systems.de\/de\/angebot\/iqdata-das-intelligente-rechenzentrum\/\" target=\"_blank\" rel=\"noopener\">iQdata RZ-L\u00f6sungen<\/a><\/li>\n<li>Informationen zum HJK Erkelenz unter: <a href=\"https:\/\/www.hjk-erkelenz.de\/\" target=\"_blank\" rel=\"noopener\">HJK-Erkelen<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Das Hermann-Josef-Krankenhaus (HJK) Erkelenz, seit 2010 auch akademisches Lehrkrankenhaus der RWTH Aachen, im nordrhein-westf\u00e4lischen Kreis Heinsberg ist ein Krankenhaus in privater Tr\u00e4gerschaft mit 409 Planbetten. Die R\u00e4umlichkeiten sind begrenzt, eine herk\u00f6mmliche L\u00f6sung nicht denkbar. Aufgrund der fortschreitenden Digitalisierung musste aber in eine leistungs- und zukunftsf\u00e4hige IT-Infrastruktur investiert werden. Den Rahmen daf\u00fcr gibt das Krankenhauszukunftsgesetz vor. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-947","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/comments?post=947"}],"version-history":[{"count":1,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/947\/revisions"}],"predecessor-version":[{"id":949,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/posts\/947\/revisions\/949"}],"wp:attachment":[{"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/media?parent=947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/categories?post=947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lan-wan-telecom.de\/index.php\/wp-json\/wp\/v2\/tags?post=947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}